[{"id":46563,"date":"2026-02-04T10:42:56","date_gmt":"2026-02-04T10:42:56","guid":{"rendered":"https:\/\/www.mailjet.com\/?post_type=case-studies&#038;p=46563"},"modified":"2026-02-04T10:42:56","modified_gmt":"2026-02-04T10:42:56","slug":"book-n-drive","status":"publish","type":"case-studies","link":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/book-n-drive\/","title":{"rendered":"book-n-drive\u00a0"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Wie book-n-drive mit Mailjet personalisierte E-Mails automatisiert und effizient skaliert<\/h2>\n\n\n\n<p>book-n-drive ist ein Carsharing-Anbieter im Rhein-Main-Gebiet und bietet sowohl stationsbasiertes Carsharing f\u00fcr geplante Fahrten als auch stationsflexibles Carsharing, bei dem Fahrzeuge spontan im Stadtgebiet genutzt und abgestellt werden k\u00f6nnen. <\/p>\n\n\n\n<p>Das Unternehmen bedient eine breite Zielgruppe &#8211; von Gelegenheitsfahrern bis zu Vielnutzern &#8211; und muss seine Kommunikation entsprechend flexibel gestalten.<\/p>\n\n\n\n<p>Mit dem Wachstum der Nutzerbasis wurde E-Mail zu einem immer wichtigeren Kanal: f\u00fcr Onboarding, Produktinformationen, Aktivierung und langfristige Kundenbindung.<\/p>\n\n\n    <div data-content-type=\"longform\" class=\"quote hub-quote longform-spacings d-flex flex-column rounded-lg px-5 py-6 px-md-6 py-md-7 p-lg-7 shadow-sm bg-primary\" data-theme=\"light\">\r\n\r\n        <div class=\"quote-logo mb-3\">\r\n                            <img decoding=\"async\" class=\"quote-logo\" src=\"https:\/\/www.mailjet.com\/wp-content\/uploads\/2026\/01\/book-n-drive-Logo_CS-scaled.png\" alt=\"Zitat-Logo von Charlotte Rothl\u00e4nder\">\r\n                    <\/div>\r\n\r\n        <blockquote class=\"quote-content content-body m-0 text-body-color\" id=\"quote-block-cfd159c9f9f2fb93d82e77b5b4ec8470\">\r\n            Mailjet \u00fcberzeugt uns durch die einfache Bedienung und den sehr guten Kundenservice.        <\/blockquote>\r\n\r\n                    <div class=\"d-flex gap-3 mt-5\">\r\n                                    <div>\r\n                        <img decoding=\"async\" width=\"72\" height=\"72\" class=\"rounded-lg quote-author\" src=\"https:\/\/www.mailjet.com\/wp-content\/uploads\/2026\/01\/Charlotte-Rothlander.jpg\" alt=\"Foto von Charlotte Rothl\u00e4nder\">\r\n                    <\/div>\r\n                                <div class=\"d-flex flex-column align-self-center fs-sm\">\r\n                    <cite class=\"mb-0 fw-bold text-accent fst-normal\" aria-describedby=\"quote-block-cfd159c9f9f2fb93d82e77b5b4ec8470\">\r\n                        Charlotte Rothl\u00e4nder                    <\/cite>\r\n                                            <span class=\"mb-0 text-body-color\">Marketing Managerin bei book-n-drive  position<\/span>\r\n                                    <\/div>\r\n            <\/div>\r\n            <\/div>\r\n\n\n\n<h2 class=\"wp-block-heading\">Herausforderung: Relevanz und Skalierbarkeit in Einklang bringen<\/h2>\n\n\n\n<p>Mit der wachsenden und immer vielf\u00e4ltigeren Nutzerbasis wurde es f\u00fcr book-n-drive zunehmend wichtiger, die Kundenkommunikation noch gezielter und pers\u00f6nlicher zu gestalten.<\/p>\n\n\n\n<p>Dabei standen folgende Anforderungen im Fokus:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Inhalte\u00a0passgenau\u00a0auf\u00a0unterschiedliche\u00a0Nutzertypen\u00a0zuschneiden\u00a0<\/li>\n\n\n\n<li>Standortbezogene\u00a0Informationen\u00a0individuell\u00a0bereitstellen\u00a0<\/li>\n\n\n\n<li>Automatisierte\u00a0Kampagnen\u00a0etablieren, um das Marketing-Team\u00a0zu\u00a0entlasten\u00a0<\/li>\n\n\n\n<li>Einen skalierbaren Versandprozess schaffen, der mit dem Wachstum Schritt h\u00e4lt<\/li>\n<\/ul>\n\n\n\n<p>book-n-drive suchte eine L\u00f6sung, die diese Anforderungen effizient und nachhaltig miteinander vereint.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Die L\u00f6sung: Struktur, Segmentierung und Automatisierung mit Mailjet<\/h2>\n\n\n\n<p>book-n-drive entschied sich f\u00fcr Mailjet, um die E-Mail-Kommunikation zentral zu strukturieren und schrittweise zu automatisieren. <\/p>\n\n\n\n<p>Die Plattform unterst\u00fctzt das Team dabei, personalisierte Newsletter effizient zu erstellen, zuversenden und den Erfolg zu messen &#8211; auch bei wachsendem Versandvolumen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Segmentierung\u00a0als\u00a0Basis<\/h3>\n\n\n\n<p>Mit den Kontaktlisten- und Segmentierungsfunktionen von Mailjet teilt book-n-drive seine Nutzer gezielt nach:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Nutzungsverhalten\u00a0<\/li>\n\n\n\n<li>Carsharing-Modell (stationsbasiert\u00a0oder\u00a0stationsflexibel)\u00a0<\/li>\n\n\n\n<li>Standort\u00a0<\/li>\n<\/ul>\n\n\n\n<p>So werden die Newsletter immer an die passende Zielgruppe verschickt &#8211; statt alle Nutzer mit den gleichen Inhalten zu erreichen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Automatisierte Workflows entlang des Nutzer-Lebenszyklus<\/h3>\n\n\n\n<p>Auf Grundlage der Segmente hat book-n-drive mehrere automatisierte E-Mail-Strecken eingerichtet, darunter:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Onboarding-Kampagnen, die\u00a0neue\u00a0Nutzer\u00a0schrittweise\u00a0an\u00a0den Service\u00a0heranf\u00fchren\u00a0<\/li>\n\n\n\n<li>Reaktivierungs-Kampagnen\u00a0f\u00fcr\u00a0inaktive\u00a0Kunden\u00a0<\/li>\n\n\n\n<li>Anlassbezogene\u00a0E-Mails\u00a0wie\u00a0Jubil\u00e4en\u00a0oder\u00a0Meilensteine\u00a0<\/li>\n<\/ul>\n\n\n\n<p>Diese automatisierten Mails werden durch definierte Ausl\u00f6ser versendet und m\u00fcssen nicht mehr manuell geplant oder verschickt werden.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Ergebnisse: Einfache\u00a0Verwaltung und\u00a0zuverl\u00e4ssiger\u00a0Versand\u00a0<\/h2>\n\n\n\n<p>Mailjet erm\u00f6glicht es dem Marketing-Team, Kampagnen, Trigger-Mails und automatisierte Strecken \u00fcbersichtlich in einem Tool zu verwalten. Die intuitive Benutzeroberfl\u00e4che erleichtert die Pflege der Newsletter, die Erstellungvon Templates und die Analyse von Kampagnenergebnissen.<\/p>\n\n\n\n<p>Dar\u00fcber hinaus sorgt Mailjet f\u00fcr eine hohe Zustellbarkeit, sodass die Newsletter zuverl\u00e4ssig im Posteingang der Empf\u00e4nger landen \u2013 und nicht im Spam. Selbst bei einem Versandvolumen von bis zu 200.000 E-Mails pro Monat bleibt die Performance stabil und skalierbar.<br><\/p>\n\n\n\n<p>Dank dieser leistungsstarken Kombination aus Segmentierung, Automatisierung und einfacher Bedienbarkeit kann book-n-drive relevante Newsletter personalisiert und effizient versenden und gleichzeitig das Marketing-Team sp\u00fcrbar entlasten.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Ausblick<\/h3>\n\n\n\n<p>In Zukunft plant book-n-drive, die vorhandenen Daten noch gezielter zu nutzen und die E-Mail-Kommunikation weiter zu verfeinern, um Relevanz und Zustellbarkeit kontinuierlich zu verbessern.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Fazit: Eine skalierbare Grundlage f\u00fcr relevante Kundenkommunikation<\/h2>\n\n\n\n<p>Mailjet stellt book-n-drive eine einfache und zuverl\u00e4ssige Plattform zur Verf\u00fcgung, um E-Mail-Kommunikation strukturiert zu segmentieren, zu automatisieren und zu skalieren.<\/p>\n\n\n\n<p>So konnte E-Mail von einem operativen Kanal zu einem zentralen Baustein der Kundenbindung werden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Erfahren Sie, wie book-n-drive mit Segmentierung und Automatisierungs-Workflows von Mailjet eine skalierbare E-Mail-Strategie aufgebaut hat, die Nutzer entlang des gesamten Lebenszyklus relevant begleitet. <\/p>\n","protected":false},"featured_media":46541,"template":"","meta":{"_acf_changed":true},"case_studies_region":[10141],"class_list":["post-46563","case-studies","type-case-studies","status-publish","has-post-thumbnail","hentry","case_studies_region-deutschland-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>book-n-drive\u00a0 - Mailjet: Email Delivery Service for Marketing &amp; Developer Teams<\/title>\n<meta name=\"description\" content=\"So\u00a0konnte\u00a0E-Mail von\u00a0einem\u00a0operativen\u00a0Kanal\u00a0zu\u00a0einem\u00a0zentralen\u00a0Baustein\u00a0der\u00a0Kundenbindung\u00a0werden.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/book-n-drive\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"book-n-drive\u00a0 - Mailjet: Email Delivery Service for Marketing &amp; Developer Teams\" \/>\n<meta property=\"og:description\" content=\"So\u00a0konnte\u00a0E-Mail von\u00a0einem\u00a0operativen\u00a0Kanal\u00a0zu\u00a0einem\u00a0zentralen\u00a0Baustein\u00a0der\u00a0Kundenbindung\u00a0werden.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/book-n-drive\/\" \/>\n<meta property=\"og:site_name\" content=\"Mailjet: Email Delivery Service for Marketing &amp; Developer Teams\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mailjet.com\/wp-content\/uploads\/2026\/01\/book-n-drive-Logo_CS-scaled.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"837\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/book-n-drive\\\/\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/book-n-drive\\\/\",\"name\":\"book-n-drive\u00a0 - Mailjet: Email Delivery Service for Marketing &amp; Developer Teams\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/book-n-drive\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/book-n-drive\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/book-n-drive-Logo_CS-scaled.png\",\"datePublished\":\"2026-02-04T10:42:56+00:00\",\"description\":\"So\u00a0konnte\u00a0E-Mail von\u00a0einem\u00a0operativen\u00a0Kanal\u00a0zu\u00a0einem\u00a0zentralen\u00a0Baustein\u00a0der\u00a0Kundenbindung\u00a0werden.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/book-n-drive\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/book-n-drive\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/book-n-drive\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/book-n-drive-Logo_CS-scaled.png\",\"contentUrl\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/book-n-drive-Logo_CS-scaled.png\",\"width\":2560,\"height\":837,\"caption\":\"book-n-drive\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/book-n-drive\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Case Studies\",\"item\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"book-n-drive\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/\",\"name\":\"Mailjet: Email Delivery Service for Marketing & Developer Teams\",\"description\":\"Discover our easy-to-use platform for designing and sending your email marketing campaigns, newsletters, and automated emails.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#organization\",\"name\":\"Mailjet: Email Delivery Service for Marketing & Developer Teams\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-mailjet-sinch.svg\",\"contentUrl\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-mailjet-sinch.svg\",\"width\":1,\"height\":1,\"caption\":\"Mailjet: Email Delivery Service for Marketing & Developer Teams\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"book-n-drive\u00a0 - Mailjet: Email Delivery Service for Marketing &amp; Developer Teams","description":"So\u00a0konnte\u00a0E-Mail von\u00a0einem\u00a0operativen\u00a0Kanal\u00a0zu\u00a0einem\u00a0zentralen\u00a0Baustein\u00a0der\u00a0Kundenbindung\u00a0werden.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/book-n-drive\/","og_locale":"de_DE","og_type":"article","og_title":"book-n-drive\u00a0 - Mailjet: Email Delivery Service for Marketing &amp; Developer Teams","og_description":"So\u00a0konnte\u00a0E-Mail von\u00a0einem\u00a0operativen\u00a0Kanal\u00a0zu\u00a0einem\u00a0zentralen\u00a0Baustein\u00a0der\u00a0Kundenbindung\u00a0werden.","og_url":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/book-n-drive\/","og_site_name":"Mailjet: Email Delivery Service for Marketing &amp; Developer Teams","og_image":[{"width":2560,"height":837,"url":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2026\/01\/book-n-drive-Logo_CS-scaled.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/book-n-drive\/","url":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/book-n-drive\/","name":"book-n-drive\u00a0 - Mailjet: Email Delivery Service for Marketing &amp; Developer Teams","isPartOf":{"@id":"https:\/\/www.mailjet.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/book-n-drive\/#primaryimage"},"image":{"@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/book-n-drive\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2026\/01\/book-n-drive-Logo_CS-scaled.png","datePublished":"2026-02-04T10:42:56+00:00","description":"So\u00a0konnte\u00a0E-Mail von\u00a0einem\u00a0operativen\u00a0Kanal\u00a0zu\u00a0einem\u00a0zentralen\u00a0Baustein\u00a0der\u00a0Kundenbindung\u00a0werden.","breadcrumb":{"@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/book-n-drive\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/book-n-drive\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/book-n-drive\/#primaryimage","url":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2026\/01\/book-n-drive-Logo_CS-scaled.png","contentUrl":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2026\/01\/book-n-drive-Logo_CS-scaled.png","width":2560,"height":837,"caption":"book-n-drive"},{"@type":"BreadcrumbList","@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/book-n-drive\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.mailjet.com\/de\/"},{"@type":"ListItem","position":2,"name":"Case Studies","item":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/"},{"@type":"ListItem","position":3,"name":"book-n-drive\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/www.mailjet.com\/de\/#website","url":"https:\/\/www.mailjet.com\/de\/","name":"Mailjet: Email Delivery Service for Marketing & Developer Teams","description":"Discover our easy-to-use platform for designing and sending your email marketing campaigns, newsletters, and automated emails.","publisher":{"@id":"https:\/\/www.mailjet.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mailjet.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.mailjet.com\/de\/#organization","name":"Mailjet: Email Delivery Service for Marketing & Developer Teams","url":"https:\/\/www.mailjet.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.mailjet.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/06\/logo-mailjet-sinch.svg","contentUrl":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/06\/logo-mailjet-sinch.svg","width":1,"height":1,"caption":"Mailjet: Email Delivery Service for Marketing & Developer Teams"},"image":{"@id":"https:\/\/www.mailjet.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/case-studies\/46563","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/case-studies"}],"about":[{"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/types\/case-studies"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/media\/46541"}],"wp:attachment":[{"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/media?parent=46563"}],"wp:term":[{"taxonomy":"case_studies_region","embeddable":true,"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/case_studies_region?post=46563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":46298,"date":"2026-01-02T14:30:34","date_gmt":"2026-01-02T14:30:34","guid":{"rendered":"https:\/\/www.mailjet.com\/resources\/case-studies\/pic-digital\/"},"modified":"2026-01-14T10:37:05","modified_gmt":"2026-01-14T10:37:05","slug":"pic-digital","status":"publish","type":"case-studies","link":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/pic-digital\/","title":{"rendered":"Pic Digital"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Entdecken Sie, wie Pic Digital sein Wachstum mit Unterkonten beschleunigt hat<\/h2>\n\n<p>Pic Digital ist eine franz\u00f6sische Web- und E-Commerce-Agentur mit Sitz in Paris und Biarritz. Sie wurde 1996 von Caroline Phillips gegr\u00fcndet. Die Agentur begleitet \u00fcber 500 Kunden bei ihren Marketing-, E-Commerce- und Entwicklungsprojekten und bietet verschiedene Schulungen an. Im Rahmen der Umsetzung neuer E-Marketing-Strategien setzt Pic Digital E-Mailing f\u00fcr seine Kunden ein, damit diese eine immer gr\u00f6\u00dfere Zielgruppe erreichen k\u00f6nnen.<\/p>\n\n<h2 class=\"wp-block-heading\">Die Herausforderung: Wie kann man eine gro\u00dfe Anzahl von Unterkonten verwalten, um die spezifischen E-Mail-Bed\u00fcrfnisse der einzelnen Kunden zu erf\u00fcllen?<\/h2>\n\n<p>Vor der Einf\u00fchrung von Sinch Mailjet testete Caroline Phillips einige andere E-Mail-Plattformen mit dem Ziel, die verschiedenen Kampagnen ihrer Kunden \u00fcber eine einzige Plattform zu verwalten. Die Einrichtung eines Unterkontos f\u00fcr jeden Kunden erwies sich jedoch stets als technische und operative Herausforderung.<\/p>\n\n<p>\u201eDie Umstellung auf Mailjet war ein echter Wendepunkt. Alles ist super einfach. Man muss nur auf \u201eEinstellungen\u201c gehen, um zu sehen, welche Zugriffsrechte den einzelnen Unterkonten gew\u00e4hrt werden.\u201c \u2013 Caroline Phillips, Gr\u00fcnderin und Gesch\u00e4ftsf\u00fchrerin<\/p>\n\n<p>Dar\u00fcber hinaus profitiert Pic Digital von den zahlreichen Funktionen, die Sinch Mailjet bietet, darunter:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Optimierte und maximierte Zustellbarkeit dank unserer Server;<\/li>\n\n\n\n<li>Automatisierte Versandprozesse zur Optimierung der Customer Journey;<\/li>\n\n\n\n<li>Funktionen zur schnelleren E-Mail-Erstellung dank k\u00fcnstlicher Intelligenz.<\/li>\n<\/ul>\n\n<p>Die Agentur sch\u00e4tzt jedoch vor allem die einfache Kommunikation mit dem Priority-Support von Sinch Mailjet. Die schnelle Bearbeitung der Tickets erm\u00f6glicht es der Agentur, Antworten auf die Fragen ihrer Kunden zu erhalten und bei Bedarf eine rasche L\u00f6sung f\u00fcr alle Arten von E-Mail-Problemen zu finden.<\/p>\n\n<h2 class=\"wp-block-heading\">Das Ergebnis: Mehr E-Mails versendet und zufriedene Kunden<\/h2>\n\n<ul class=\"wp-block-list\">\n<li>Viele Arbeitsstunden und Aufwand f\u00fcr die Konfiguration von Unterkonten gespart: Die vereinfachte Erstellung und Verwaltung von Sinch Mailjet-Unterkonten hat die Akzeptanz von E-Mailings bei den Kunden der Agentur beschleunigt und allen Beteiligten viel Zeit gespart.<\/li>\n\n\n\n<li>St\u00e4ndig steigendes Volumen beim E-Mail-Versand: Der E-Mail-Versand von Pic Digital f\u00fcr seine Kunden hat zugenommen, und die durchschnittlichen \u00d6ffnungsraten sind innerhalb von 12 Monaten von 25\u00a0% auf \u00fcber 30\u00a0% gestiegen \u2013 nicht nur eine quantitative, sondern auch eine qualitative Verbesserung des Versands.<\/li>\n<\/ul>\n    <div data-content-type=\"longform\" class=\"quote hub-quote longform-spacings d-flex flex-column rounded-lg px-5 py-6 px-md-6 py-md-7 p-lg-7 shadow-sm bg-primary\" data-theme=\"light\">\r\n\r\n        <div class=\"quote-logo mb-3\">\r\n                            <svg height=\"40\" class=\"quote-icon quote-icon-color\" aria-hidden=\"true\" data-url=\"https:\/\/www.mailjet.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/custom-icons\/quotes-right.svg\"><\/svg>\r\n                    <\/div>\r\n\r\n        <blockquote class=\"quote-content content-body m-0 text-body-color\" id=\"quote-block-28cc96434f1c4820ca1a134044363ab3\">\r\n            Die E-Mail hat einen echten Zweck, und ist bei weitem nicht so aufdringlich wie eine SMS oder eine telefonische Benachrichtigung. Die E-Mail hat ihren Platz.        <\/blockquote>\r\n\r\n                    <div class=\"d-flex gap-3 mt-5\">\r\n                                    <div>\r\n                        <img decoding=\"async\" width=\"72\" height=\"72\" class=\"rounded-lg quote-author\" src=\"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/11\/Capture-decran-2025-11-27-a-10.31.16.png\" alt=\"Foto von Caroline Phillips\">\r\n                    <\/div>\r\n                                <div class=\"d-flex flex-column align-self-center fs-sm\">\r\n                    <cite class=\"mb-0 fw-bold text-accent fst-normal\" aria-describedby=\"quote-block-28cc96434f1c4820ca1a134044363ab3\">\r\n                        Caroline Phillips                    <\/cite>\r\n                                            <span class=\"mb-0 text-body-color\">Gr\u00fcnderin und Gesch\u00e4ftsf\u00fchrerin, Pic Digital<\/span>\r\n                                    <\/div>\r\n            <\/div>\r\n            <\/div>\r\n\n<p>Sehen Sie sich das Interview an, das Caroline Phillips uns \u00fcber ihre Beziehung zu Sinch Mailjet gegeben hat (Video auf Franz\u00f6sisch, englische Untertitel verf\u00fcgbar).<\/p>\n\t<div class=\"custom-video\">\r\n\t\t\t\t\t                    <div class=\"iframe-responsive-container lazy-video rounded-lg overflow-hidden \">\r\n                <a href=\"https:\/\/www.youtube.com\/watch?v=FYhPq6jUdJE\" class=\"lazy-video-link\" data-lazy-video=\"FYhPq6jUdJE\" target=\"_blank\" rel=\"nofollow\" role=\"button\" data-source=\"youtube\" data-language=\"de\" data-thumb=\"https:\/\/img.youtube.com\/vi\/FYhPq6jUdJE\/maxresdefault.jpg\" title=\"Sinch-Video\">\r\n                    <div class=\"btn btn-light btn-light-social btn-play btn-play-circle\">\r\n                                                    <svg aria-hidden=\"true\" data-url=\"https:\/\/www.mailjet.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/play.svg\"><\/svg>\r\n                                            <\/div>\r\n                    <img decoding=\"async\"  src=\"https:\/\/img.youtube.com\/vi\/FYhPq6jUdJE\/maxresdefault.jpg\" alt=\"Comment l&#039;agence Pic Digital utilise l&#039;emailing avec Mailjet\">\r\n                <\/a>\r\n            <\/div>\r\n                        <script type=\"application\/ld+json\">\r\n            {\n    \"@context\": \"http:\/\/schema.org\",\n    \"@type\": \"VideoObject\",\n    \"@id\": \"https:\/\/www.youtube.com\/watch?v=FYhPq6jUdJE#VideoObject\",\n    \"thumbnailUrl\": \"https:\/\/img.youtube.com\/vi\/FYhPq6jUdJE\/maxresdefault.jpg\",\n    \"embedUrl\": \"https:\/\/www.youtube.com\/embed\/FYhPq6jUdJE\",\n    \"contentUrl\": \"https:\/\/www.youtube.com\/watch?v=FYhPq6jUdJE\",\n    \"name\": \"Comment l'agence Pic Digital utilise l'emailing avec Mailjet\",\n    \"description\": \"Caroline Phillips, CEO de l'agence Pic Digital, nous explique comment les fonctionnalit\\u00e9s de sous-comptes, d'automatisation, et de cr\\u00e9ation assist\\u00e9e par IA de Sinch Mailjet ont aid\\u00e9 son entreprise \\u00e0 cro\\u00eetre, et quelle place occupe l'email dans une strat\\u00e9gie de marketing omnicanale.\\n\\n#emailing #agence\",\n    \"uploadDate\": \"2025-11-14T14:59:10+00:00\",\n    \"duration\": \"PT1M47S\"\n}        <\/script>\r\n        \t\t\r\n\t\t\t<\/div>\r\n\r\n\t\r\n","protected":false},"excerpt":{"rendered":"<p>Erfahren Sie, wie die Agentur Pic Digital die Verwaltung des E-Mail-Versands f\u00fcr ihre Kunden vereinfacht und beschleunigt hat und wie sie dank Sinch Mailjet-Unterkonten die \u00d6ffnungsraten auf 30&nbsp;% steigern konnte.<\/p>\n","protected":false},"featured_media":46044,"template":"","meta":{"_acf_changed":false},"case_studies_region":[10138],"class_list":["post-46298","case-studies","type-case-studies","status-publish","has-post-thumbnail","hentry","case_studies_region-frankreich-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pic Digital: E-Mailing f\u00fcr Agenturen<\/title>\n<meta name=\"description\" content=\"Erfahren Sie, wie Pic Digital die Vorteile von Unterkonten wirksam einsetzt, um die E-Mail-Strategien seiner Kunden zu erweitern und zu beschleunigen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/pic-digital\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pic Digital: E-Mailing f\u00fcr Agenturen\" \/>\n<meta property=\"og:description\" content=\"Erfahren Sie, wie Pic Digital die Vorteile von Unterkonten wirksam einsetzt, um die E-Mail-Strategien seiner Kunden zu erweitern und zu beschleunigen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/pic-digital\/\" \/>\n<meta property=\"og:site_name\" content=\"Mailjet: Email Delivery Service for Marketing &amp; Developer Teams\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-14T10:37:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/11\/picdigital-casestudy.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"496\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/pic-digital\\\/\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/pic-digital\\\/\",\"name\":\"Pic Digital: E-Mailing f\u00fcr Agenturen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/pic-digital\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/pic-digital\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/picdigital-casestudy.jpg\",\"datePublished\":\"2026-01-02T14:30:34+00:00\",\"dateModified\":\"2026-01-14T10:37:05+00:00\",\"description\":\"Erfahren Sie, wie Pic Digital die Vorteile von Unterkonten wirksam einsetzt, um die E-Mail-Strategien seiner Kunden zu erweitern und zu beschleunigen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/pic-digital\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/pic-digital\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/pic-digital\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/picdigital-casestudy.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/picdigital-casestudy.jpg\",\"width\":800,\"height\":496,\"caption\":\"Pic Digital\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/pic-digital\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Case Studies\",\"item\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pic Digital\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/\",\"name\":\"Mailjet: Email Delivery Service for Marketing & Developer Teams\",\"description\":\"Discover our easy-to-use platform for designing and sending your email marketing campaigns, newsletters, and automated emails.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#organization\",\"name\":\"Mailjet: Email Delivery Service for Marketing & Developer Teams\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-mailjet-sinch.svg\",\"contentUrl\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-mailjet-sinch.svg\",\"width\":1,\"height\":1,\"caption\":\"Mailjet: Email Delivery Service for Marketing & Developer Teams\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pic Digital: E-Mailing f\u00fcr Agenturen","description":"Erfahren Sie, wie Pic Digital die Vorteile von Unterkonten wirksam einsetzt, um die E-Mail-Strategien seiner Kunden zu erweitern und zu beschleunigen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/pic-digital\/","og_locale":"de_DE","og_type":"article","og_title":"Pic Digital: E-Mailing f\u00fcr Agenturen","og_description":"Erfahren Sie, wie Pic Digital die Vorteile von Unterkonten wirksam einsetzt, um die E-Mail-Strategien seiner Kunden zu erweitern und zu beschleunigen.","og_url":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/pic-digital\/","og_site_name":"Mailjet: Email Delivery Service for Marketing &amp; Developer Teams","article_modified_time":"2026-01-14T10:37:05+00:00","og_image":[{"width":800,"height":496,"url":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/11\/picdigital-casestudy.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/pic-digital\/","url":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/pic-digital\/","name":"Pic Digital: E-Mailing f\u00fcr Agenturen","isPartOf":{"@id":"https:\/\/www.mailjet.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/pic-digital\/#primaryimage"},"image":{"@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/pic-digital\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/11\/picdigital-casestudy.jpg","datePublished":"2026-01-02T14:30:34+00:00","dateModified":"2026-01-14T10:37:05+00:00","description":"Erfahren Sie, wie Pic Digital die Vorteile von Unterkonten wirksam einsetzt, um die E-Mail-Strategien seiner Kunden zu erweitern und zu beschleunigen.","breadcrumb":{"@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/pic-digital\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/pic-digital\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/pic-digital\/#primaryimage","url":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/11\/picdigital-casestudy.jpg","contentUrl":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/11\/picdigital-casestudy.jpg","width":800,"height":496,"caption":"Pic Digital"},{"@type":"BreadcrumbList","@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/pic-digital\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.mailjet.com\/de\/"},{"@type":"ListItem","position":2,"name":"Case Studies","item":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/"},{"@type":"ListItem","position":3,"name":"Pic Digital"}]},{"@type":"WebSite","@id":"https:\/\/www.mailjet.com\/de\/#website","url":"https:\/\/www.mailjet.com\/de\/","name":"Mailjet: Email Delivery Service for Marketing & Developer Teams","description":"Discover our easy-to-use platform for designing and sending your email marketing campaigns, newsletters, and automated emails.","publisher":{"@id":"https:\/\/www.mailjet.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mailjet.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.mailjet.com\/de\/#organization","name":"Mailjet: Email Delivery Service for Marketing & Developer Teams","url":"https:\/\/www.mailjet.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.mailjet.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/06\/logo-mailjet-sinch.svg","contentUrl":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/06\/logo-mailjet-sinch.svg","width":1,"height":1,"caption":"Mailjet: Email Delivery Service for Marketing & Developer Teams"},"image":{"@id":"https:\/\/www.mailjet.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/case-studies\/46298","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/case-studies"}],"about":[{"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/types\/case-studies"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/media\/46044"}],"wp:attachment":[{"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/media?parent=46298"}],"wp:term":[{"taxonomy":"case_studies_region","embeddable":true,"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/case_studies_region?post=46298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":46145,"date":"2025-12-10T08:46:49","date_gmt":"2025-12-10T08:46:49","guid":{"rendered":"https:\/\/www.mailjet.com\/?post_type=case-studies&#038;p=46145"},"modified":"2026-02-25T11:05:59","modified_gmt":"2026-02-25T11:05:59","slug":"burson","status":"publish","type":"case-studies","link":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/burson\/","title":{"rendered":"Burson"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Reibungslose globale Kommunikation: Wie Burson mit Sinch Mailjet den E-Mail-Versand in 43 M\u00e4rkten vereinheitlicht<\/h2>\n\n\n\n<p>F\u00fcr <a href=\"https:\/\/www.bursonglobal.com\/\">Burson<\/a>, eine weltweit agierende Kommunikationsagentur, ist E-Mail der wichtigste Kanal zur Kundenkommunikation. Doch mit der Zeit entwickelten sich in den 43 M\u00e4rkten eigene Tools und Prozesse \u2013 ein fragmentiertes System, das die Performance-Analyse, Einhaltung von Standards und Zustellbarkeit erschwerte. Burson suchte daher eine zentrale L\u00f6sung, die alle Teams zufriedenstellen konnte.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">L\u00f6sung: Das richtige Ma\u00df an Kontrolle und Flexibilit\u00e4t finden<\/h2>\n\n\n\n<p>Nach der Evaluierung von mehr als 30 E-Mail-Plattformen entschied sich Burson f\u00fcr Sinch Mailjet. Seitdem profitieren alle Teams, die auf E-Mail angewiesen sind, von:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Einem flexiblen, <a href=\"https:\/\/www.mailjet.com\/de\/produkte\/email-marketing\/email-editor\/\">benutzerfreundlichen E-Mail-Editor<\/a> f\u00fcr einfache und individuell gestaltete Kampagnen<\/li>\n\n\n\n<li>Funktionen zur Listenverwaltung und <a href=\"https:\/\/www.mailjet.com\/de\/produkte\/email-marketing\/segmentierung\/\">Segmentierung<\/a>, um relevante, personalisierte Inhalte zu versenden \u2013 konform mit Opt-in\/Opt-out-Anforderungen in allen M\u00e4rkten<\/li>\n\n\n\n<li>Automatischer Listenhygiene zur Entfernung von Bounces, Erkennung ung\u00fcltiger Adressen und Pflege von Sperrlisten<\/li>\n\n\n\n<li><a href=\"https:\/\/www.mailjet.com\/de\/produkte\/email-marketing\/tracking-tools\/\">Echtzeit-Einblicke in Kampagnen-Performance<\/a>, inkl. \u00d6ffnungs-, Klick- und Interaktionsraten<\/li>\n<\/ul>\n\n\n\n<p><strong>Innerhalb von drei Monaten<\/strong> hat Burson mit Unterst\u00fctzung des engagierten Onboarding-Teams von Sinch Mailjet <strong>Tausende von Mitarbeitern seines Agenturnetzwerks auf die neue Plattform umgestellt<\/strong>. Dazu geh\u00f6rten praxisorientierte Produktschulungen, Q&amp;A-Sessions und der Zugang zu einer Online-Ressourcenplattform. Zus\u00e4tzlich richtete Sinch Mailjet <strong>f\u00fcr jede Niederlassung eine eigene Subdomain <\/strong>ein, um die Domain-Reputation zu sichern und die Zustellbarkeit zu verbessern.<\/p>\n\n\n    <div data-content-type=\"longform\" class=\"quote hub-quote longform-spacings d-flex flex-column rounded-lg px-5 py-6 px-md-6 py-md-7 p-lg-7 shadow-sm bg-sand\" data-theme=\"light\">\r\n\r\n        <div class=\"quote-logo mb-3\">\r\n                            <img decoding=\"async\" class=\"quote-logo\" src=\"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/12\/Burson-Icon.jpg\" alt=\"Zitat-Logo von Maria Vasiliev\">\r\n                    <\/div>\r\n\r\n        <blockquote class=\"quote-content content-body m-0 text-body-color\" id=\"quote-block-c380611921b43df7a7b3a48ad24be4c6\">\r\n            Mailjet bietet uns die perfekte Balance aus Kontrolle und Flexibilit\u00e4t sowie globale Standardisierung bei gleichzeitiger lokaler Anpassungsf\u00e4higkeit.        <\/blockquote>\r\n\r\n                    <div class=\"d-flex gap-3 mt-5\">\r\n                                <div class=\"d-flex flex-column align-self-center fs-sm\">\r\n                    <cite class=\"mb-0 fw-bold text-accent fst-normal\" aria-describedby=\"quote-block-c380611921b43df7a7b3a48ad24be4c6\">\r\n                        Maria Vasiliev                    <\/cite>\r\n                                            <span class=\"mb-0 text-body-color\">Product Lead bei Burson<\/span>\r\n                                    <\/div>\r\n            <\/div>\r\n            <\/div>\r\n\n\n\n<h2 class=\"wp-block-heading\">Ergebnis: Engagement und Zustellbarkeit auf neuem Niveau<\/h2>\n\n\n\n<p class=\"has-text-align-left\">Dank Sinch Mailjet konnte die globale Kommunikationsagentur Burson ihre E-Mail-Kommunikation weltweit standardisieren und das Versandvolumen monatlich verdoppeln. Heute versenden die erfolgreichsten Teams \u00fcber 100.000 E-Mails pro Monat.<\/p>\n\n\n\n<p>Mit den Analyse- und Reporting-Funktionen von Sinch Mailjet kann Burson die Performance \u00fcber alle M\u00e4rkte hinweg messen, seine Engagement-Strategie gezielt anpassen und die Kampagnenwirkung optimieren. Die durchschnittliche \u00d6ffnungsrate liegt bei 30 % \u2013 deutlich \u00fcber dem <a href=\"https:\/\/dma.org.uk\/article\/email-benchmarking-report-2018\">B2B-Benchmark von 15,1 %.<\/a> Auch die Zustellrate bleibt konstant \u00fcber 90 % und \u00fcbertrifft damit den <a href=\"https:\/\/www.emailtooltester.com\/en\/blog\/email-deliverability-statistics\/\">branchen\u00fcblichen Schnitt von 83,1 %<\/a>. Besonders im B2B-Umfeld mit seinen strengeren Filtern ist das beachtlich.<\/p>\n\n\n\n<p>Die Umstellung auf Sinch Mailjet wirkte sich zudem positiv auf Bursons Domain-Reputation aus. Die integrierten Reporting-Tools sowie individuelle Empfehlungen des <a href=\"https:\/\/www.mailjet.com\/de\/produkte\/zustellbarkeit\/expertenhilfe-zustellbarkeit\/\">Zustellbarkeits-Support-Teams<\/a> lieferten konkrete Ma\u00dfnahmen zur Kontaktpflege, die Zustellbarkeit und Reputation weiter verbessern.<\/p>\n\n\n\n<p class=\"has-text-align-left\">Heute verf\u00fcgt jedes Team \u00fcber eine eigene Subdomain. So kann jedes Team unabh\u00e4ngig agieren und gleichzeitig die Hauptdomain sch\u00fctzen. Viele dieser Subdomains haben bereits eine hohe Reputation aufgebaut \u2013 best\u00e4tigt durch Google Postmaster Tools.<\/p>\n\n\n    <div data-content-type=\"longform\" class=\"quote hub-quote longform-spacings d-flex flex-column rounded-lg px-5 py-6 px-md-6 py-md-7 p-lg-7 shadow-sm bg-sand\" data-theme=\"light\">\r\n\r\n        <div class=\"quote-logo mb-3\">\r\n                            <img decoding=\"async\" class=\"quote-logo\" src=\"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/12\/Burson-Icon.jpg\" alt=\"Zitat-Logo von Maria Vasiliev\">\r\n                    <\/div>\r\n\r\n        <blockquote class=\"quote-content content-body m-0 text-body-color\" id=\"quote-block-2630ac3920c6759368de219c266059c2\">\r\n            Mit Sinch Mailjet haben wir in nur drei Monaten einen reibungslosen, skalierbaren und effizienten E-Mail-Versand in gro\u00dfem Umfang in 43 M\u00e4rkten erm\u00f6glicht.         <\/blockquote>\r\n\r\n                    <div class=\"d-flex gap-3 mt-5\">\r\n                                <div class=\"d-flex flex-column align-self-center fs-sm\">\r\n                    <cite class=\"mb-0 fw-bold text-accent fst-normal\" aria-describedby=\"quote-block-2630ac3920c6759368de219c266059c2\">\r\n                        Maria Vasiliev                    <\/cite>\r\n                                            <span class=\"mb-0 text-body-color\">Product Lead bei Burson<\/span>\r\n                                    <\/div>\r\n            <\/div>\r\n            <\/div>\r\n\n\n\n<p>Mit einer skalierbaren, datengest\u00fctzten E-Mail-L\u00f6sung st\u00e4rkt Burson seine Teams und schafft weltweit bessere Kundenerlebnisse.&nbsp;<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Erfahren Sie, wie eine f\u00fchrende globale Kommunikationsagentur ihre E-Mail-Systeme vereinfachte, lokale Teams st\u00e4rkte und die Kundenbindung steigerte.<\/p>\n","protected":false},"featured_media":46291,"template":"","meta":{"_acf_changed":true},"case_studies_region":[88,90,10137],"class_list":["post-46145","case-studies","type-case-studies","status-publish","has-post-thumbnail","hentry","case_studies_region-deutschland","case_studies_region-usa","case_studies_region-usa-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>E-Mail-L\u00f6sung f\u00fcr Agenturen: Burson setzt auf Sinch Mailjet<\/title>\n<meta name=\"description\" content=\"Wie Burson mit Mailjet eine zentrale E-Mail-L\u00f6sung f\u00fcr 43 M\u00e4rkte fand \u2013 ideal f\u00fcr Agenturen, die Kontrolle und Lokalanpassung verbinden wollen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/burson\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"E-Mail-L\u00f6sung f\u00fcr Agenturen: Burson setzt auf Sinch Mailjet\" \/>\n<meta property=\"og:description\" content=\"Wie Burson mit Mailjet eine zentrale E-Mail-L\u00f6sung f\u00fcr 43 M\u00e4rkte fand \u2013 ideal f\u00fcr Agenturen, die Kontrolle und Lokalanpassung verbinden wollen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/burson\/\" \/>\n<meta property=\"og:site_name\" content=\"Mailjet: Email Delivery Service for Marketing &amp; Developer Teams\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-25T11:05:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/12\/MJ-CS-Burson.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"496\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/burson\\\/\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/burson\\\/\",\"name\":\"E-Mail-L\u00f6sung f\u00fcr Agenturen: Burson setzt auf Sinch Mailjet\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/burson\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/burson\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/MJ-CS-Burson.jpg\",\"datePublished\":\"2025-12-10T08:46:49+00:00\",\"dateModified\":\"2026-02-25T11:05:59+00:00\",\"description\":\"Wie Burson mit Mailjet eine zentrale E-Mail-L\u00f6sung f\u00fcr 43 M\u00e4rkte fand \u2013 ideal f\u00fcr Agenturen, die Kontrolle und Lokalanpassung verbinden wollen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/burson\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/burson\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/burson\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/MJ-CS-Burson.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/MJ-CS-Burson.jpg\",\"width\":800,\"height\":496},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/burson\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Case Studies\",\"item\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Burson\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/\",\"name\":\"Mailjet: Email Delivery Service for Marketing & Developer Teams\",\"description\":\"Discover our easy-to-use platform for designing and sending your email marketing campaigns, newsletters, and automated emails.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#organization\",\"name\":\"Mailjet: Email Delivery Service for Marketing & Developer Teams\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-mailjet-sinch.svg\",\"contentUrl\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-mailjet-sinch.svg\",\"width\":1,\"height\":1,\"caption\":\"Mailjet: Email Delivery Service for Marketing & Developer Teams\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"E-Mail-L\u00f6sung f\u00fcr Agenturen: Burson setzt auf Sinch Mailjet","description":"Wie Burson mit Mailjet eine zentrale E-Mail-L\u00f6sung f\u00fcr 43 M\u00e4rkte fand \u2013 ideal f\u00fcr Agenturen, die Kontrolle und Lokalanpassung verbinden wollen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/burson\/","og_locale":"de_DE","og_type":"article","og_title":"E-Mail-L\u00f6sung f\u00fcr Agenturen: Burson setzt auf Sinch Mailjet","og_description":"Wie Burson mit Mailjet eine zentrale E-Mail-L\u00f6sung f\u00fcr 43 M\u00e4rkte fand \u2013 ideal f\u00fcr Agenturen, die Kontrolle und Lokalanpassung verbinden wollen.","og_url":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/burson\/","og_site_name":"Mailjet: Email Delivery Service for Marketing &amp; Developer Teams","article_modified_time":"2026-02-25T11:05:59+00:00","og_image":[{"width":800,"height":496,"url":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/12\/MJ-CS-Burson.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/burson\/","url":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/burson\/","name":"E-Mail-L\u00f6sung f\u00fcr Agenturen: Burson setzt auf Sinch Mailjet","isPartOf":{"@id":"https:\/\/www.mailjet.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/burson\/#primaryimage"},"image":{"@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/burson\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/12\/MJ-CS-Burson.jpg","datePublished":"2025-12-10T08:46:49+00:00","dateModified":"2026-02-25T11:05:59+00:00","description":"Wie Burson mit Mailjet eine zentrale E-Mail-L\u00f6sung f\u00fcr 43 M\u00e4rkte fand \u2013 ideal f\u00fcr Agenturen, die Kontrolle und Lokalanpassung verbinden wollen.","breadcrumb":{"@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/burson\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/burson\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/burson\/#primaryimage","url":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/12\/MJ-CS-Burson.jpg","contentUrl":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/12\/MJ-CS-Burson.jpg","width":800,"height":496},{"@type":"BreadcrumbList","@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/burson\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.mailjet.com\/de\/"},{"@type":"ListItem","position":2,"name":"Case Studies","item":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/"},{"@type":"ListItem","position":3,"name":"Burson"}]},{"@type":"WebSite","@id":"https:\/\/www.mailjet.com\/de\/#website","url":"https:\/\/www.mailjet.com\/de\/","name":"Mailjet: Email Delivery Service for Marketing & Developer Teams","description":"Discover our easy-to-use platform for designing and sending your email marketing campaigns, newsletters, and automated emails.","publisher":{"@id":"https:\/\/www.mailjet.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mailjet.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.mailjet.com\/de\/#organization","name":"Mailjet: Email Delivery Service for Marketing & Developer Teams","url":"https:\/\/www.mailjet.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.mailjet.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/06\/logo-mailjet-sinch.svg","contentUrl":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/06\/logo-mailjet-sinch.svg","width":1,"height":1,"caption":"Mailjet: Email Delivery Service for Marketing & Developer Teams"},"image":{"@id":"https:\/\/www.mailjet.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/case-studies\/46145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/case-studies"}],"about":[{"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/types\/case-studies"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/media\/46291"}],"wp:attachment":[{"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/media?parent=46145"}],"wp:term":[{"taxonomy":"case_studies_region","embeddable":true,"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/case_studies_region?post=46145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":46095,"date":"2025-12-05T13:37:54","date_gmt":"2025-12-05T13:37:54","guid":{"rendered":"https:\/\/www.mailjet.com\/resources\/case-studies\/aprendemas-com\/"},"modified":"2025-12-10T08:52:26","modified_gmt":"2025-12-10T08:52:26","slug":"aprendemas-com","status":"publish","type":"case-studies","link":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/aprendemas-com\/","title":{"rendered":"Aprendem\u00e1s.com"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Einleitung<\/h2>\n\n<p>Aprendemas.com ist ein Portal f\u00fcr die Suche nach Schulen, Akademien, Universit\u00e4ten und Ausbildungszentren, wo die Benutzer dank einer leistungsstarken Suchmaschine, die eine Filterung nach Schl\u00fcsselw\u00f6rtern, Provinzen oder Kategorien erm\u00f6glicht, die Schulen, Akademien, Universit\u00e4ten und Ausbildungszentren finden k\u00f6nnen, die sie suchen. Aprendemas.com hat sich mit Mailjet zusammengetan, um seine Nutzer per E-Mail \u00fcber die neuesten Kurse und Stipendien zu informieren und ihnen dabei zu helfen, die besten Zentren zu finden, in denen sie sich pers\u00f6nlich und beruflich weiterbilden k\u00f6nnen.<\/p>\n\n<h2 class=\"wp-block-heading\">Die Herausforderung<\/h2>\n\n<p>Urspr\u00fcnglich arbeitete Aprendemas.com mit einem anderen E-Mail-Anbieter, aber dessen hoher Preis und seine Tools, die im Vergleich zu denen anderer Plattformen zu veralten begannen, veranlassten sie, sich nach einer moderneren und kosteng\u00fcnstigeren Alternative umzusehen. Bei seiner Suche beschr\u00e4nkte Aprendemas.com seine Optionen auf zwei: Mailjet und eine andere E-Mail-L\u00f6sung. Letztendlich gaben die wirklich niedrigen Preise der anderen Alternative den Ausschlag f\u00fcr diese Plattform. Die Erfahrungen von Aprendemas.com mit diesem anderen E-Mail-Anbieter waren jedoch nicht nur nicht so gut wie erwartet, sondern hatten auch negative Auswirkungen auf die E-Mail-Strategie des Unternehmens. Die Unterst\u00fctzung w\u00e4hrend der IP-Aufw\u00e4rmphase war sehr begrenzt, und das Team von Aprendemas.com f\u00fchlte sich auf sich allein gestellt und hatte kaum eine Chance, die Hilfe zu bekommen, die es brauchte, um seine E-Mail-Strategie auf den Weg zu bringen.<\/p>\n\n<h2 class=\"wp-block-heading\">Die L\u00f6sung<\/h2>\n\n<p>Am Ende entschied sich Aprendemas.com aufgrund des guten Preis-Leistungs-Verh\u00e4ltnisses unserer L\u00f6sung, aber vor allem wegen der Betreuung und des Vertrauens, das das Team vom ersten Kontakt an ausstrahlte, f\u00fcr Mailjet, um seine E-Mail-Marketing-Strategie zu starten. Das Customer Success-Team von Mailjet stand Aprendemas.com von Anfang an zur Seite, um den richtigen, ma\u00dfgeschneiderten Plan f\u00fcr ihre E-Mail-Strategie zu finden, unterst\u00fctzte sie w\u00e4hrend der IP-Aufw\u00e4rmphase und bereitete sie auf den sicheren Versand ihres gesch\u00e4tzten Volumens von 30 Millionen E-Mails pro Jahr vor. Dank dieser anf\u00e4nglichen Arbeit hat Aprendemas.com einen ausgezeichneten Ruf bei Google, Outlook, Yahoo, AOL und anderen E-Mail-Clients erlangt, was zu einem Anstieg der \u00d6ffnungs- und Klickraten und einer Verbesserung der Kundenkonversionsrate von 10% in den ersten Monaten seit Beginn dieser Partnerschaft gef\u00fchrt hat. Dar\u00fcber hinaus hat Aprendemas.com die Vorteile unseres leistungsstarken und intuitiven Drag-and-Drop-E-Mail-Editors voll ausgesch\u00f6pft und so Zeit und Entwicklungskosten f\u00fcr die Gestaltung von Kampagnen eingespart.<\/p>\n    <div data-content-type=\"longform\" class=\"quote hub-quote longform-spacings d-flex flex-column rounded-lg px-5 py-6 px-md-6 py-md-7 p-lg-7 shadow-sm bg-primary\" data-theme=\"light\">\r\n\r\n        <div class=\"quote-logo mb-3\">\r\n                            <img decoding=\"async\" class=\"quote-logo\" src=\"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/05\/Aprendemas-logo.png\" alt=\"Zitat-Logo von Enrique Reyes\">\r\n                    <\/div>\r\n\r\n        <blockquote class=\"quote-content content-body m-0 text-body-color\" id=\"quote-block-955f9003b621e188bd8d04876c7990f3\">\r\n            Der Service, den Mailjet uns bietet, ist der beste Wert, insbesondere die Qualit\u00e4t aller beteiligten Personen, von der kommerziellen Seite bis zum technischen Service. Insbesondere unser Customer Success Manager, der uns beraten, Zweifel ausger\u00e4umt und uns geholfen hat, diese neue Phase erfolgreich zu starten.        <\/blockquote>\r\n\r\n                    <div class=\"d-flex gap-3 mt-5\">\r\n                                    <div>\r\n                        <img decoding=\"async\" width=\"72\" height=\"72\" class=\"rounded-lg quote-author\" src=\"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/01\/Portrait-Enrique-Reyes-Aprendemas.png\" alt=\"Foto von Enrique Reyes\">\r\n                    <\/div>\r\n                                <div class=\"d-flex flex-column align-self-center fs-sm\">\r\n                    <cite class=\"mb-0 fw-bold text-accent fst-normal\" aria-describedby=\"quote-block-955f9003b621e188bd8d04876c7990f3\">\r\n                        Enrique Reyes                    <\/cite>\r\n                                            <span class=\"mb-0 text-body-color\">CTO &#8211; Aprendemas.com<\/span>\r\n                                    <\/div>\r\n            <\/div>\r\n            <\/div>\r\n\n<h2 class=\"wp-block-heading\">Die Vision<\/h2>\n\n<p>Das Ziel der E-Mail-Strategie von Aprendemas.com besteht darin, neue Wege zu finden, um die von den Benutzern gew\u00fcnschten Informationen effektiv, schnell und sicher bereitzustellen.<\/p>\n    <div data-content-type=\"longform\" class=\"quote hub-quote longform-spacings d-flex flex-column rounded-lg px-5 py-6 px-md-6 py-md-7 p-lg-7 shadow-sm bg-primary\" data-theme=\"light\">\r\n\r\n        <div class=\"quote-logo mb-3\">\r\n                            <img decoding=\"async\" class=\"quote-logo\" src=\"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/05\/Aprendemas-logo.png\" alt=\"Zitat-Logo von Enrique Reyes\">\r\n                    <\/div>\r\n\r\n        <blockquote class=\"quote-content content-body m-0 text-body-color\" id=\"quote-block-5af7e90ceaa75a5bc270765517e2c506\">\r\n            Unsere Erfahrung mit unserem E-Mail-Anbieter war nicht gut, da der technische Support nur wenig Unterst\u00fctzung beim Aufw\u00e4rmen der zugewiesenen IP bot. Wir f\u00fchlten uns auf uns allein gestellt und merkten schnell, dass dies nicht das richtige Marketinginstrument f\u00fcr uns war. Dank der Beratung durch Mailjet und der gemeinsamen Erarbeitung eines angemessenen und ma\u00dfgeschneiderten Plans zur Erw\u00e4rmung der IPs haben wir einen ausgezeichneten Ruf bei Google, Microsoft (Hotmail und Outlook), Yahoo, AOL usw. erworben. In nur 3 Monaten haben wir die \u00d6ffnungs- und Klickraten sowie die Conversion Rate unserer Kunden um mehr als 10&nbsp;% gesteigert.        <\/blockquote>\r\n\r\n                    <div class=\"d-flex gap-3 mt-5\">\r\n                                    <div>\r\n                        <img decoding=\"async\" width=\"72\" height=\"72\" class=\"rounded-lg quote-author\" src=\"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/01\/Portrait-Enrique-Reyes-Aprendemas.png\" alt=\"Foto von Enrique Reyes\">\r\n                    <\/div>\r\n                                <div class=\"d-flex flex-column align-self-center fs-sm\">\r\n                    <cite class=\"mb-0 fw-bold text-accent fst-normal\" aria-describedby=\"quote-block-5af7e90ceaa75a5bc270765517e2c506\">\r\n                        Enrique Reyes                    <\/cite>\r\n                                            <span class=\"mb-0 text-body-color\">CTO &#8211; Aprendemas.com<\/span>\r\n                                    <\/div>\r\n            <\/div>\r\n            <\/div>\r\n\n<p>Zu diesem Zweck werden Mailjet und Aprendemas.com weiterhin Hand in Hand arbeiten, um eine E-Mail-Strategie zu entwerfen, die den ausgezeichneten Ruf des Unternehmens als Absender bewahrt und den Nutzern von Suchmaschinen einen Mehrwert bietet, indem sie deren \u00d6ffnungs- und Klickraten verbessert.<\/p>\n    <div data-content-type=\"longform\" class=\"longform-spacings\">\r\n        <div class=\"cta bg-primary rounded-lg px-5 py-6 p-md-7 px-md-6\">\r\n                    <div class=\"form-subscription\">\r\n                            <div class=\"h4 mb-3\">\r\n                    Immer auf dem neuesten Stand. Abonnieren Sie unseren Newsletter und erhalten Sie wertvolle Ressourcen direkt in Ihr Postfach.                <\/div>\r\n                                    <form accept-charset=\"UTF-8\" action=\"\" enctype=\"multipart\/form-data\" data-form-subscription method=\"POST\" style=\"max-width: 400px;\">\r\n                <div class=\"row justify-content-between align-items-top g-2\">\r\n                    <div class=\"col-10\">\r\n                        <input type=\"email\" name=\"email\" class=\"form-control\" placeholder=\"Email\" autocomplete=\"email\" required>\r\n                        <div data-fs=\"error\" role=\"alert\" class=\"invalid-feedback\">\r\n                            Please complete this required field.                        <\/div>\r\n                    <\/div>\r\n                                            <div class=\"col-12 order-last mt-3 fs-xxs\" data-fs=\"acceptance\" style=\"display:none;\">\r\n                            \r\n                                <div class=\"form-check\">\r\n                                    <input id=\"formSubscriptionAcceptance-terms-2295\" class=\"form-check-input\"\r\n                                        type=\"checkbox\" name=\"terms\">\r\n                                    <label for=\"formSubscriptionAcceptance-terms-2295\" class=\"form-check-label text-body-color\">\r\n                                        Ich habe die Servicebedingungen gelesen und stimme ihnen zu.                                        <span class=\"hs-form-required\">*<\/span>\r\n                                    <\/label>\r\n                                <\/div>\r\n\r\n                            \r\n                                <div class=\"form-check\">\r\n                                    <input id=\"formSubscriptionAcceptance-privacy-1986\" class=\"form-check-input\"\r\n                                        type=\"checkbox\" name=\"privacy\">\r\n                                    <label for=\"formSubscriptionAcceptance-privacy-1986\" class=\"form-check-label text-body-color\">\r\n                                        Ich habe die Datenschutzerkl\u00e4rung gelesen und bin damit einverstanden.                                        <span class=\"hs-form-required\">*<\/span>\r\n                                    <\/label>\r\n                                <\/div>\r\n\r\n                                                    <\/div>\r\n                    \r\n                                            <div class=\"col-12 order-last fs-xxs mb-0 mt-2 text-body-color\">\r\n                            Ja, ich m\u00f6chte den Mailjet-Newsletter abonnieren.                        <\/div>\r\n                    \r\n                    <div class=\"col-2\">\r\n                        <button type=\"submit\" value=\"Submit\" aria-label=\"Submit\" class=\"btn btn-secondary btn-icon\">\r\n                            <svg aria-hidden=\"true\" data-url=\"https:\/\/www.mailjet.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/layout\/chevron-right.svg\"><\/svg>\r\n                        <\/button>\r\n                    <\/div>\r\n                <\/div>\r\n\r\n                <input type=\"hidden\" name=\"formSubscriptionRecaptchaToken\" data-fs=\"recaptcha-token\">\r\n\r\n            <\/form>\r\n            <div data-fs=\"message-success\" style=\"display: none;\">\r\n                <p class=\"mb-0 mt-2 text-body-color\">\r\n                    Pr\u00fcfen Sie Ihren Posteingang jeden Monat auf Ihren Mailjet Newsletter!                <\/p>\r\n            <\/div>\r\n        <\/div>\r\n        <\/div>\r\n    <\/div>\r\n","protected":false},"excerpt":{"rendered":"<p>Aprendemas.com arbeitet mit Mailjet zusammen, um seine E-Mail-Strategie zu verbessern<\/p>\n","protected":false},"featured_media":38244,"template":"","meta":{"_acf_changed":false},"case_studies_region":[10140],"class_list":["post-46095","case-studies","type-case-studies","status-publish","has-post-thumbnail","hentry","case_studies_region-spanien-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aprendem\u00e1s.com - Mailjet: Email Delivery Service for Marketing &amp; Developer Teams<\/title>\n<meta name=\"description\" content=\"Aprendemas.com nutzt Mailjet, um gezielte E-Mail-Updates zu Kursen und Stipendien zu versenden und Studenten dabei zu helfen, ganz einfach die besten Ausbildungszentren zu finden.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/aprendemas-com\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aprendem\u00e1s.com - Mailjet: Email Delivery Service for Marketing &amp; Developer Teams\" \/>\n<meta property=\"og:description\" content=\"Aprendemas.com nutzt Mailjet, um gezielte E-Mail-Updates zu Kursen und Stipendien zu versenden und Studenten dabei zu helfen, ganz einfach die besten Ausbildungszentren zu finden.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/aprendemas-com\/\" \/>\n<meta property=\"og:site_name\" content=\"Mailjet: Email Delivery Service for Marketing &amp; Developer Teams\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-10T08:52:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/01\/MJ-CS-Aprendemas.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"992\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/aprendemas-com\\\/\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/aprendemas-com\\\/\",\"name\":\"Aprendem\u00e1s.com - Mailjet: Email Delivery Service for Marketing &amp; Developer Teams\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/aprendemas-com\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/aprendemas-com\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/MJ-CS-Aprendemas.png\",\"datePublished\":\"2025-12-05T13:37:54+00:00\",\"dateModified\":\"2025-12-10T08:52:26+00:00\",\"description\":\"Aprendemas.com nutzt Mailjet, um gezielte E-Mail-Updates zu Kursen und Stipendien zu versenden und Studenten dabei zu helfen, ganz einfach die besten Ausbildungszentren zu finden.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/aprendemas-com\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/aprendemas-com\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/aprendemas-com\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/MJ-CS-Aprendemas.png\",\"contentUrl\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/MJ-CS-Aprendemas.png\",\"width\":1600,\"height\":992},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/aprendemas-com\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Case Studies\",\"item\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Aprendem\u00e1s.com\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/\",\"name\":\"Mailjet: Email Delivery Service for Marketing & Developer Teams\",\"description\":\"Discover our easy-to-use platform for designing and sending your email marketing campaigns, newsletters, and automated emails.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#organization\",\"name\":\"Mailjet: Email Delivery Service for Marketing & Developer Teams\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-mailjet-sinch.svg\",\"contentUrl\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-mailjet-sinch.svg\",\"width\":1,\"height\":1,\"caption\":\"Mailjet: Email Delivery Service for Marketing & Developer Teams\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aprendem\u00e1s.com - Mailjet: Email Delivery Service for Marketing &amp; Developer Teams","description":"Aprendemas.com nutzt Mailjet, um gezielte E-Mail-Updates zu Kursen und Stipendien zu versenden und Studenten dabei zu helfen, ganz einfach die besten Ausbildungszentren zu finden.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/aprendemas-com\/","og_locale":"de_DE","og_type":"article","og_title":"Aprendem\u00e1s.com - Mailjet: Email Delivery Service for Marketing &amp; Developer Teams","og_description":"Aprendemas.com nutzt Mailjet, um gezielte E-Mail-Updates zu Kursen und Stipendien zu versenden und Studenten dabei zu helfen, ganz einfach die besten Ausbildungszentren zu finden.","og_url":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/aprendemas-com\/","og_site_name":"Mailjet: Email Delivery Service for Marketing &amp; Developer Teams","article_modified_time":"2025-12-10T08:52:26+00:00","og_image":[{"width":1600,"height":992,"url":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/01\/MJ-CS-Aprendemas.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/aprendemas-com\/","url":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/aprendemas-com\/","name":"Aprendem\u00e1s.com - Mailjet: Email Delivery Service for Marketing &amp; Developer Teams","isPartOf":{"@id":"https:\/\/www.mailjet.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/aprendemas-com\/#primaryimage"},"image":{"@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/aprendemas-com\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/01\/MJ-CS-Aprendemas.png","datePublished":"2025-12-05T13:37:54+00:00","dateModified":"2025-12-10T08:52:26+00:00","description":"Aprendemas.com nutzt Mailjet, um gezielte E-Mail-Updates zu Kursen und Stipendien zu versenden und Studenten dabei zu helfen, ganz einfach die besten Ausbildungszentren zu finden.","breadcrumb":{"@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/aprendemas-com\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/aprendemas-com\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/aprendemas-com\/#primaryimage","url":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/01\/MJ-CS-Aprendemas.png","contentUrl":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/01\/MJ-CS-Aprendemas.png","width":1600,"height":992},{"@type":"BreadcrumbList","@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/aprendemas-com\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.mailjet.com\/de\/"},{"@type":"ListItem","position":2,"name":"Case Studies","item":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/"},{"@type":"ListItem","position":3,"name":"Aprendem\u00e1s.com"}]},{"@type":"WebSite","@id":"https:\/\/www.mailjet.com\/de\/#website","url":"https:\/\/www.mailjet.com\/de\/","name":"Mailjet: Email Delivery Service for Marketing & Developer Teams","description":"Discover our easy-to-use platform for designing and sending your email marketing campaigns, newsletters, and automated emails.","publisher":{"@id":"https:\/\/www.mailjet.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mailjet.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.mailjet.com\/de\/#organization","name":"Mailjet: Email Delivery Service for Marketing & Developer Teams","url":"https:\/\/www.mailjet.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.mailjet.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/06\/logo-mailjet-sinch.svg","contentUrl":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/06\/logo-mailjet-sinch.svg","width":1,"height":1,"caption":"Mailjet: Email Delivery Service for Marketing & Developer Teams"},"image":{"@id":"https:\/\/www.mailjet.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/case-studies\/46095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/case-studies"}],"about":[{"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/types\/case-studies"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/media\/38244"}],"wp:attachment":[{"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/media?parent=46095"}],"wp:term":[{"taxonomy":"case_studies_region","embeddable":true,"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/case_studies_region?post=46095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":46094,"date":"2025-12-05T13:37:51","date_gmt":"2025-12-05T13:37:51","guid":{"rendered":"https:\/\/www.mailjet.com\/resources\/case-studies\/exoticca\/"},"modified":"2025-12-10T08:53:33","modified_gmt":"2025-12-10T08:53:33","slug":"exoticca","status":"publish","type":"case-studies","link":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/exoticca\/","title":{"rendered":"Exoticca"},"content":{"rendered":"\n<p><strong>Einleitung<\/strong><\/p>\n\n<p>Exoticca wurde 2014 gegr\u00fcndet und ist das erste spanische Online-Reiseb\u00fcro 100%, das sich auf einzigartige Reiseerlebnisse zu exotischen Reisezielen zu einem sehr g\u00fcnstigen Preis spezialisiert hat. Die Angebote von Exoticca sind f\u00fcr eine begrenzte Zeit auf der Website verf\u00fcgbar und konzentrieren sich auf Mittel- oder Fernreiseziele, die nach Themen wie Touren, Str\u00e4nde, Natur oder St\u00e4dte geordnet sind.<\/p>\n\n<p>E-Mail-Marketing ist f\u00fcr Exoticca eine der wichtigsten Strategien zur Steigerung des Umsatzes. Als das Unternehmen begann, in andere europ\u00e4ische L\u00e4nder zu expandieren, entschied es sich f\u00fcr eine Partnerschaft mit Mailjet, da es eine skalierbare Plattform ben\u00f6tigte, die sich nahtlos an sein schnelles Wachstum anpassen und einen schnelleren und engeren Support-Service bieten konnte.<\/p>\n\n<p>Heute verschickt Exoticca seine w\u00f6chentlichen Newsletter in vier verschiedenen Sprachen an 50\u00a0000 Kontakte in Europa und den Vereinigten Staaten.<\/p>\n\n<p><strong>Die Herausforderung<\/strong><\/p>\n\n<p>Der bisherige E-Mail-Anbieter von Exoticca bot ein veraltetes Tool zur Erstellung von Kampagnen, das nicht flexibel und intuitiv genug war, damit jeder Marketingpartner E-Mail-Vorlagen einfach bearbeiten und gestalten konnte. Au\u00dferdem war die Behebung von Vorf\u00e4llen, die das System betrafen, recht langsam und kostspielig und wurde immer von einem anderen Support-Mitarbeiter durchgef\u00fchrt.<\/p>\n\n<p>Angesichts der angestrebten Internationalisierung war Exoticca auf der Suche nach einer E-Mail-Plattform, die nicht nur flexibel und sicher ist, sondern auch kontinuierlichen Support und Beratung durch Experten f\u00fcr Zustellbarkeit und bew\u00e4hrte E-Mail-Verfahren bietet, damit sich das Unternehmen auf das konzentrieren kann, was wirklich wichtig ist: das Wachstum seines Unternehmens.<\/p>\n\n<p>\u201eWir standen vor einer neuen Phase in unserem Unternehmen. Wir mussten uns internationalisieren und eine neue globale E-Mail-Marketingstrategie einf\u00fchren, also brauchten wir ein Tool, das dieser Aufgabe gewachsen war.\u201c<\/p>\n\n<p><strong>Die L\u00f6sung<\/strong><\/p>\n\n<p>Exoticca fand in Mailjet einen Partner mit einer soliden und zuverl\u00e4ssigen Struktur, wodurch die Zahl der technischen Zwischenf\u00e4lle, die normalerweise die Arbeit des Unternehmens behinderten, reduziert werden konnte. Dar\u00fcber hinaus ist der E-Mail-Editor sehr intuitiv und einfach zu bedienen, was die Erstellung von Newslettern erleichtert und der Marketingabteilung die M\u00f6glichkeit gibt, kreativer zu arbeiten, ohne dass spezielle Kenntnisse erforderlich sind.<\/p>\n\n<p>F\u00fcr Samuel Mart\u00ed, Leiter des E-Mail-Marketings bei Exoticca, hat sich der Service jedoch durch die engagierte Betreuung von anderen Wettbewerbern abgehoben: &#8222;Die Beziehung zu unserem Customer Success Manager war einer der Mehrwerte, die Mailjet uns geboten hat, und das hat uns zweifelsohne dazu gebracht, bei dieser Plattform zu bleiben. Die Beziehung ist direkt und eng, und die Antworten auf unsere Fragen sind unmittelbar.&#8220;<\/p>\n\n<p>Was sie an dieser Zahl am meisten sch\u00e4tzen, ist das technische Wissen, das sie ihnen vermitteln (z. B. \u00fcber Zustellbarkeit, IP-Reputation oder sogar Branchentrends) und vor allem die guten Versandpraktiken, die ihre E-Mail-Marketingstrategie erfolgreich machen. Dank ihrer gemeinsamen Arbeit hat Exoticca eine optimale IP-Reputation bei allen E-Mail-Clients erreicht (in einigen F\u00e4llen von 55\u00a0% auf 90\u00a0%) und damit eine qualitative Verbesserung ihrer KPIs.<\/p>\n\n<p><strong>Die Vision<\/strong><\/p>\n\n<p>Die Arbeit von Exoticca und Mailjet hat eine klare Zukunftsperspektive. In K\u00fcrze plant das Unternehmen, automatisierte E-Mail-Kampagnen zu starten, um alle Informationen, die es bereits \u00fcber seine Kontakte hat, zu nutzen, und die leistungsstarke API von Mailjet auch f\u00fcr die Verwaltung seiner Transaktionsmails einzusetzen.<\/p>\n    <div data-content-type=\"longform\" class=\"quote hub-quote longform-spacings d-flex flex-column rounded-lg px-5 py-6 px-md-6 py-md-7 p-lg-7 shadow-sm bg-primary\" data-theme=\"light\">\r\n\r\n        <div class=\"quote-logo mb-3\">\r\n                            <img decoding=\"async\" class=\"quote-logo\" src=\"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/01\/exoticca.svg\" alt=\"Zitat-Logo von Samuel Mart\u00ed\">\r\n                    <\/div>\r\n\r\n        <blockquote class=\"quote-content content-body m-0 text-body-color\" id=\"quote-block-7b69d519978a42143b870b846651ef86\">\r\n            \u201eWir begannen die Zusammenarbeit mit Mailjet und erhielten vom ersten Moment an eine sehr enge, aber vor allem sehr professionelle Unterst\u00fctzung. Wir k\u00f6nnen jetzt sagen, dass wir eine klare Strategie haben, mit einer internationalen Perspektive und mit der wir auch unsere \u00d6ffnungs- und Klickraten verbessert haben. Aber das ist noch nicht alles, wir arbeiten weiter und unsere n\u00e4chste Herausforderung konzentriert sich auf Wachstum und Prozessautomatisierung zur Steigerung unserer Effizienz.\u201c          <\/blockquote>\r\n\r\n                    <div class=\"d-flex gap-3 mt-5\">\r\n                                    <div>\r\n                        <img decoding=\"async\" width=\"72\" height=\"72\" class=\"rounded-lg quote-author\" src=\"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/01\/Portrait-Samuel-Marti-Exoticca.png\" alt=\"Foto von Samuel Mart\u00ed\">\r\n                    <\/div>\r\n                                <div class=\"d-flex flex-column align-self-center fs-sm\">\r\n                    <cite class=\"mb-0 fw-bold text-accent fst-normal\" aria-describedby=\"quote-block-7b69d519978a42143b870b846651ef86\">\r\n                        Samuel Mart\u00ed                    <\/cite>\r\n                                            <span class=\"mb-0 text-body-color\">Leitung E-Mail-Marketing &#8211; Exoticca<\/span>\r\n                                    <\/div>\r\n            <\/div>\r\n            <\/div>\r\n    <div data-content-type=\"longform\" class=\"longform-spacings\">\r\n        <div class=\"cta bg-primary rounded-lg px-5 py-6 p-md-7 px-md-6\">\r\n                    <div class=\"form-subscription\">\r\n                            <div class=\"h4 mb-3\">\r\n                    Immer auf dem neuesten Stand. Abonnieren Sie unseren Newsletter und erhalten Sie wertvolle Ressourcen direkt in Ihr Postfach.                <\/div>\r\n                                    <form accept-charset=\"UTF-8\" action=\"\" enctype=\"multipart\/form-data\" data-form-subscription method=\"POST\" style=\"max-width: 400px;\">\r\n                <div class=\"row justify-content-between align-items-top g-2\">\r\n                    <div class=\"col-10\">\r\n                        <input type=\"email\" name=\"email\" class=\"form-control\" placeholder=\"Email\" autocomplete=\"email\" required>\r\n                        <div data-fs=\"error\" role=\"alert\" class=\"invalid-feedback\">\r\n                            Please complete this required field.                        <\/div>\r\n                    <\/div>\r\n                                            <div class=\"col-12 order-last mt-3 fs-xxs\" data-fs=\"acceptance\" style=\"display:none;\">\r\n                            \r\n                                <div class=\"form-check\">\r\n                                    <input id=\"formSubscriptionAcceptance-terms-2450\" class=\"form-check-input\"\r\n                                        type=\"checkbox\" name=\"terms\">\r\n                                    <label for=\"formSubscriptionAcceptance-terms-2450\" class=\"form-check-label text-body-color\">\r\n                                        Ich habe die Servicebedingungen gelesen und stimme ihnen zu.                                        <span class=\"hs-form-required\">*<\/span>\r\n                                    <\/label>\r\n                                <\/div>\r\n\r\n                            \r\n                                <div class=\"form-check\">\r\n                                    <input id=\"formSubscriptionAcceptance-privacy-5366\" class=\"form-check-input\"\r\n                                        type=\"checkbox\" name=\"privacy\">\r\n                                    <label for=\"formSubscriptionAcceptance-privacy-5366\" class=\"form-check-label text-body-color\">\r\n                                        Ich habe die Datenschutzerkl\u00e4rung gelesen und bin damit einverstanden.                                        <span class=\"hs-form-required\">*<\/span>\r\n                                    <\/label>\r\n                                <\/div>\r\n\r\n                                                    <\/div>\r\n                    \r\n                                            <div class=\"col-12 order-last fs-xxs mb-0 mt-2 text-body-color\">\r\n                            Ja, ich m\u00f6chte den Mailjet-Newsletter abonnieren.                        <\/div>\r\n                    \r\n                    <div class=\"col-2\">\r\n                        <button type=\"submit\" value=\"Submit\" aria-label=\"Submit\" class=\"btn btn-secondary btn-icon\">\r\n                            <svg aria-hidden=\"true\" data-url=\"https:\/\/www.mailjet.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/layout\/chevron-right.svg\"><\/svg>\r\n                        <\/button>\r\n                    <\/div>\r\n                <\/div>\r\n\r\n                <input type=\"hidden\" name=\"formSubscriptionRecaptchaToken\" data-fs=\"recaptcha-token\">\r\n\r\n            <\/form>\r\n            <div data-fs=\"message-success\" style=\"display: none;\">\r\n                <p class=\"mb-0 mt-2 text-body-color\">\r\n                    Schauen Sie monatlich in Ihren Posteingang, um Ihren Sinch Newsletter zu erhalten.                <\/p>\r\n            <\/div>\r\n        <\/div>\r\n        <\/div>\r\n    <\/div>\r\n","protected":false},"excerpt":{"rendered":"<p>Exoticca arbeitet mit Mailjet zusammen, um seine globale E-Mail-Strategie umzusetzen<\/p>\n","protected":false},"featured_media":38254,"template":"","meta":{"_acf_changed":false},"case_studies_region":[10140],"class_list":["post-46094","case-studies","type-case-studies","status-publish","has-post-thumbnail","hentry","case_studies_region-spanien-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Exoticca - Mailjet: Email Delivery Service for Marketing &amp; Developer Teams<\/title>\n<meta name=\"description\" content=\"Exoticca nutzt Mailjet, um sein E-Mail-Marketing zu skalieren, w\u00e4hrend es in ganz Europa expandiert und w\u00f6chentlich mehrsprachige Newsletter an 50\u00a0000 Reiseabonnenten versendet.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/exoticca\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exoticca - Mailjet: Email Delivery Service for Marketing &amp; Developer Teams\" \/>\n<meta property=\"og:description\" content=\"Exoticca nutzt Mailjet, um sein E-Mail-Marketing zu skalieren, w\u00e4hrend es in ganz Europa expandiert und w\u00f6chentlich mehrsprachige Newsletter an 50\u00a0000 Reiseabonnenten versendet.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/exoticca\/\" \/>\n<meta property=\"og:site_name\" content=\"Mailjet: Email Delivery Service for Marketing &amp; Developer Teams\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-10T08:53:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/01\/MJ-CS-Exoticca-1024x635.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"635\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/exoticca\\\/\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/exoticca\\\/\",\"name\":\"Exoticca - Mailjet: Email Delivery Service for Marketing &amp; Developer Teams\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/exoticca\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/exoticca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/MJ-CS-Exoticca.png\",\"datePublished\":\"2025-12-05T13:37:51+00:00\",\"dateModified\":\"2025-12-10T08:53:33+00:00\",\"description\":\"Exoticca nutzt Mailjet, um sein E-Mail-Marketing zu skalieren, w\u00e4hrend es in ganz Europa expandiert und w\u00f6chentlich mehrsprachige Newsletter an 50\u00a0000 Reiseabonnenten versendet.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/exoticca\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/exoticca\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/exoticca\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/MJ-CS-Exoticca.png\",\"contentUrl\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/MJ-CS-Exoticca.png\",\"width\":1600,\"height\":992},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/exoticca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Case Studies\",\"item\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Exoticca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/\",\"name\":\"Mailjet: Email Delivery Service for Marketing & Developer Teams\",\"description\":\"Discover our easy-to-use platform for designing and sending your email marketing campaigns, newsletters, and automated emails.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#organization\",\"name\":\"Mailjet: Email Delivery Service for Marketing & Developer Teams\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-mailjet-sinch.svg\",\"contentUrl\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-mailjet-sinch.svg\",\"width\":1,\"height\":1,\"caption\":\"Mailjet: Email Delivery Service for Marketing & Developer Teams\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exoticca - Mailjet: Email Delivery Service for Marketing &amp; Developer Teams","description":"Exoticca nutzt Mailjet, um sein E-Mail-Marketing zu skalieren, w\u00e4hrend es in ganz Europa expandiert und w\u00f6chentlich mehrsprachige Newsletter an 50\u00a0000 Reiseabonnenten versendet.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/exoticca\/","og_locale":"de_DE","og_type":"article","og_title":"Exoticca - Mailjet: Email Delivery Service for Marketing &amp; Developer Teams","og_description":"Exoticca nutzt Mailjet, um sein E-Mail-Marketing zu skalieren, w\u00e4hrend es in ganz Europa expandiert und w\u00f6chentlich mehrsprachige Newsletter an 50\u00a0000 Reiseabonnenten versendet.","og_url":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/exoticca\/","og_site_name":"Mailjet: Email Delivery Service for Marketing &amp; Developer Teams","article_modified_time":"2025-12-10T08:53:33+00:00","og_image":[{"width":1024,"height":635,"url":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/01\/MJ-CS-Exoticca-1024x635.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/exoticca\/","url":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/exoticca\/","name":"Exoticca - Mailjet: Email Delivery Service for Marketing &amp; Developer Teams","isPartOf":{"@id":"https:\/\/www.mailjet.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/exoticca\/#primaryimage"},"image":{"@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/exoticca\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/01\/MJ-CS-Exoticca.png","datePublished":"2025-12-05T13:37:51+00:00","dateModified":"2025-12-10T08:53:33+00:00","description":"Exoticca nutzt Mailjet, um sein E-Mail-Marketing zu skalieren, w\u00e4hrend es in ganz Europa expandiert und w\u00f6chentlich mehrsprachige Newsletter an 50\u00a0000 Reiseabonnenten versendet.","breadcrumb":{"@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/exoticca\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/exoticca\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/exoticca\/#primaryimage","url":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/01\/MJ-CS-Exoticca.png","contentUrl":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/01\/MJ-CS-Exoticca.png","width":1600,"height":992},{"@type":"BreadcrumbList","@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/exoticca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.mailjet.com\/de\/"},{"@type":"ListItem","position":2,"name":"Case Studies","item":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/"},{"@type":"ListItem","position":3,"name":"Exoticca"}]},{"@type":"WebSite","@id":"https:\/\/www.mailjet.com\/de\/#website","url":"https:\/\/www.mailjet.com\/de\/","name":"Mailjet: Email Delivery Service for Marketing & Developer Teams","description":"Discover our easy-to-use platform for designing and sending your email marketing campaigns, newsletters, and automated emails.","publisher":{"@id":"https:\/\/www.mailjet.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mailjet.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.mailjet.com\/de\/#organization","name":"Mailjet: Email Delivery Service for Marketing & Developer Teams","url":"https:\/\/www.mailjet.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.mailjet.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/06\/logo-mailjet-sinch.svg","contentUrl":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/06\/logo-mailjet-sinch.svg","width":1,"height":1,"caption":"Mailjet: Email Delivery Service for Marketing & Developer Teams"},"image":{"@id":"https:\/\/www.mailjet.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/case-studies\/46094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/case-studies"}],"about":[{"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/types\/case-studies"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/media\/38254"}],"wp:attachment":[{"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/media?parent=46094"}],"wp:term":[{"taxonomy":"case_studies_region","embeddable":true,"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/case_studies_region?post=46094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":45891,"date":"2025-11-11T15:32:07","date_gmt":"2025-11-11T15:32:07","guid":{"rendered":"https:\/\/www.mailjet.com\/?post_type=case-studies&#038;p=45891"},"modified":"2026-02-25T11:05:31","modified_gmt":"2026-02-25T11:05:31","slug":"outdooractive","status":"publish","type":"case-studies","link":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/outdooractive\/","title":{"rendered":"Outdooractive"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><strong>Wie Outdooractive mit Mailjet mit \u00fcber 300 Mio. E-Mails im Jahr und komplexer Segmentierung seine Spamrate unter 0,1% h\u00e4lt<\/strong><\/h2>\n\n\n\n<p><a href=\"https:\/\/www.outdooractive.com\/de\/\">Outdooractive <\/a>ist mit \u00fcber 60 Millionen Nutzern, 8.500 B2B-Partnern und mehr als 1,5 Millionen Touren Europas gr\u00f6\u00dfte Plattform f\u00fcr Outdoor-Erlebnisse.<\/p>\n\n\n\n<p>Die Herausforderung: Ein hohes E-Mail-Volumen \u2013 generiert durch Community-Kommunikation, automatisierte Systemmails und B2B-Kampagnen \u2013 muss zuverl\u00e4ssig und personalisiert versendet werden. Um Inhalte konsistent, datenschutzkonform und zielgerichtet auszuspielen, braucht das Team ein Setup, das trotz vieler interner Beteiligter effizient, skalierbar und transparent bleibt.<\/p>\n\n\n\n<p>Die vorherige L\u00f6sung war weder flexibel genug, um verschiedene E-Mail-Typen effizient zu steuern, noch intuitiv genug, damit alle Teams reibungslos damit arbeiten konnten.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">L\u00f6sung: Ein E-Mail-Set-up, das mitw\u00e4chst<\/h2>\n\n\n\n<p>Um den wachsenden Anforderungen an ihren E-Mail-Versand gerecht zu werden, setzt Outdooractive auf eine L\u00f6sung, die sowohl zuverl\u00e4ssige Automatismen als auch kreativen Spielraum bietet. Im Zentrum steht ein Set-up, das Zusammenarbeit erleichtert und gleichzeitig die Kontrolle \u00fcber Versandprozesse und die Effizienz der Mailings wahrt.<\/p>\n\n\n\n<p>Mit Sinch Mailjet hat das Team die passende L\u00f6sung gefunden, um unterschiedliche E-Mail-Typen effizient und im einheitlichen Look zuverl\u00e4ssig in die Postf\u00e4cher seiner Kunden zu bringen.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Plattform &amp; API \u2013 flexibel kombiniert: <\/strong>Outdooractive nutzt Mailjets intuitiven <a href=\"https:\/\/www.mailjet.com\/de\/produkte\/email-marketing\/email-editor\/\">E-Mail-Editor<\/a> f\u00fcr redaktionelle Inhalte und Freigaben, die <a href=\"https:\/\/www.mailjet.com\/de\/produkte\/email-api\/\">Mailjet Email API<\/a> f\u00fcr automatisierte Abl\u00e4ufe wie Nutzerdaten- und Newsletter-Sync. So bleibt der Versand effizient, integriert und skalierbar.<\/li>\n\n\n\n<li><strong>Modulare E-Mail-Vorlagen:<\/strong> Vorgefertigte, gebrandete Templates und wiederverwendbare Bausteine sichern konsistente Kommunikation im gesamten Team \u2013 mit minimalem Aufwand.<\/li>\n\n\n\n<li><strong>Personalisierung in gro\u00dfem Stil:<\/strong> Outdooractive versendet jede Woche neben diversen anderen Emails auch durchschnittlich 3,5 Millionen personalisierte \u201eFor You\u201c-E-Mails in vier Sprachen \u2013 abgestimmt auf Sprache, Interessen und Verhalten der Empf\u00e4nger. <a href=\"https:\/\/www.mailjet.com\/de\/produkte\/email-marketing\/segmentierung\/\">Mailjets erweiterte Segmentierung<\/a> erm\u00f6glicht eine pr\u00e4zise Zielgruppenansprache, w\u00e4hrend dynamische Inhaltsbl\u00f6cke automatisch die passenden Inhalte ausspielen. Automatisierte Kampagnen sorgen daf\u00fcr, dass jede Nachricht zur richtigen Zeit im richtigen Postfach landet \u2013 markenkonform und skalierbar.<\/li>\n\n\n\n<li><strong>Effiziente Freigabeprozesse:<\/strong> Dank <a href=\"https:\/\/www.mailjet.com\/de\/produkte\/email-marketing\/echtzeit-zusammenarbeit\/\">integrierter Kommentar- und Kollaborationstools <\/a>spart das Team Zeit und vermeidet Reibungsverluste \u2013 auch wenn mehrere Abteilungen beteiligt sind.<\/li>\n\n\n\n<li><strong>Nachhaltig versenden mit System: <\/strong>Outdooractive setzt auf saubere Listen, geringe Spamraten und hohe Zustellbarkeit. Mailjet unterst\u00fctzt mit automatischer Listenpflege, Zustellanalyse und dem gezielten Ausschluss inaktiver Kontakte \u2013 f\u00fcr zuverl\u00e4ssige Zustellung bei den richtigen Empf\u00e4ngern.<\/li>\n<\/ul>\n\n\n\n<p>Das Ganze wird erg\u00e4nzt durch einen <a href=\"https:\/\/www.mailjet.com\/de\/produkte\/zustellbarkeit\/expertenhilfe-zustellbarkeit\/\">pers\u00f6nlichen Technical Account Manager<\/a>, der direkt bei Herausforderungen hilft \u2013 ob bei API-Fragen, Template-Einrichtung oder Zustellbarkeit.<\/p>\n\n\n    <div data-content-type=\"longform\" class=\"quote hub-quote longform-spacings d-flex flex-column rounded-lg px-5 py-6 px-md-6 py-md-7 p-lg-7 shadow-sm bg-sand\" data-theme=\"light\">\r\n\r\n        <div class=\"quote-logo mb-3\">\r\n                            <img decoding=\"async\" class=\"quote-logo\" src=\"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/11\/Untitled-design-7.png\" alt=\"Zitat-Logo von Pirmin M\u00f6sle\">\r\n                    <\/div>\r\n\r\n        <blockquote class=\"quote-content content-body m-0 text-body-color\" id=\"quote-block-8c1bee89a501fb98f968009ea1a3cc8a\">\r\n            F\u00fcr uns stimmt mit Sinch Mailjet nicht nur das technische Set-up, sondern auch die Beratung und der Support. Unser pers\u00f6nlicher Technical Account Manager bei Sinch Mailjet hilft uns, unsere Zustellraten konstant \u00fcber 96% zu halten.        <\/blockquote>\r\n\r\n                    <div class=\"d-flex gap-3 mt-5\">\r\n                                    <div>\r\n                        <img decoding=\"async\" width=\"72\" height=\"72\" class=\"rounded-lg quote-author\" src=\"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/11\/Pirmin-Mosle_CTO_Outdooractive.jpeg\" alt=\"Foto von Pirmin M\u00f6sle\">\r\n                    <\/div>\r\n                                <div class=\"d-flex flex-column align-self-center fs-sm\">\r\n                    <cite class=\"mb-0 fw-bold text-accent fst-normal\" aria-describedby=\"quote-block-8c1bee89a501fb98f968009ea1a3cc8a\">\r\n                        Pirmin M\u00f6sle                    <\/cite>\r\n                                            <span class=\"mb-0 text-body-color\">CTO von Outdooractive<\/span>\r\n                                    <\/div>\r\n            <\/div>\r\n            <\/div>\r\n\n\n\n<h2 class=\"wp-block-heading\">Ergebnis: Mehr Tempo, weniger Aufwand<\/h2>\n\n\n\n<p>So schafft Outdooractive eine skalierbare E-Mail-Infrastruktur, die sowohl Massenversand als auch gezielte Ansprache zuverl\u00e4ssig abdeckt \u2013 abgestimmt auf verschiedene Zielgruppen und Anwendungsbereiche.<\/p>\n\n\n\n<p>Seit dem Einsatz von Mailjet kann Outdooractive E-Mail-Kampagnen schneller erstellen, pr\u00e4ziser aussteuern und sicher zustellen. Die intuitive Mailjet E-Mail-Editor erleichtert es auch nicht-technischen Teams, Inhalte selbstst\u00e4ndig zu gestalten.<\/p>\n\n\n\n<p>Dank modularer Vorlagen bleibt die Markenidentit\u00e4t gewahrt, w\u00e4hrend die API-Anbindung Daten automatisch synchronisiert und manuelle Arbeitsschritte reduziert. Kollaborationsfunktionen beschleunigen interne Abstimmungen, und saubere Listenpflege sorgt f\u00fcr eine <strong>Zustellrate von \u00fcber 96 %<\/strong> und eine <strong>Spamrate von unter 0,01 %<\/strong> \u2013 bei konstant hohen \u00d6ffnungsraten. Zum Vergleich: <a href=\"https:\/\/www.emailtooltester.com\/de\/email-deliverability-test\/\">Branchenweit liegt die durchschnittliche Zustellrate bei etwa 85,1 %<\/a> (Quelle: Emailtooltester) und die Spamrate bei rund 0,1 % \u2013 Outdooractive \u00fcbertrifft diese Werte deutlich.<\/p>\n\n\n    <div data-content-type=\"longform\" class=\"quote hub-quote longform-spacings d-flex flex-column rounded-lg px-5 py-6 px-md-6 py-md-7 p-lg-7 shadow-sm bg-sand\" data-theme=\"light\">\r\n\r\n        <div class=\"quote-logo mb-3\">\r\n                            <img decoding=\"async\" class=\"quote-logo\" src=\"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/11\/Untitled-design-7.png\" alt=\"Zitat-Logo von Pirmin M\u00f6sle\">\r\n                    <\/div>\r\n\r\n        <blockquote class=\"quote-content content-body m-0 text-body-color\" id=\"quote-block-0baaf9d3413bf57b5a1549eb8f6174a4\">\r\n            Mailjet ist eine sehr leistungsstarke E-Mail-L\u00f6sung aus der Sinch Communication Cloud. Die weiteren Produkte von Sinch bieten f\u00fcr uns eine skalierbare Basis, um alle Use Cases unsere Kundenkommunikation aus einer Hand zu gestalten.        <\/blockquote>\r\n\r\n                    <div class=\"d-flex gap-3 mt-5\">\r\n                                    <div>\r\n                        <img decoding=\"async\" width=\"72\" height=\"72\" class=\"rounded-lg quote-author\" src=\"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/11\/Pirmin-Mosle_CTO_Outdooractive.jpeg\" alt=\"Foto von Pirmin M\u00f6sle\">\r\n                    <\/div>\r\n                                <div class=\"d-flex flex-column align-self-center fs-sm\">\r\n                    <cite class=\"mb-0 fw-bold text-accent fst-normal\" aria-describedby=\"quote-block-0baaf9d3413bf57b5a1549eb8f6174a4\">\r\n                        Pirmin M\u00f6sle                    <\/cite>\r\n                                            <span class=\"mb-0 text-body-color\">CTO von Outdooractive<\/span>\r\n                                    <\/div>\r\n            <\/div>\r\n            <\/div>\r\n","protected":false},"excerpt":{"rendered":"<p>Erfahren Sie, wie das Tech-Unternehmen aus dem Tourismus trotz komplexer Segmentierung und 300 Millionen E-Mails pro Jahr eine durchschnittliche Zustellrate von 96 % erreicht.<\/p>\n","protected":false},"featured_media":46023,"template":"","meta":{"_acf_changed":true},"case_studies_region":[88,10141],"class_list":["post-45891","case-studies","type-case-studies","status-publish","has-post-thumbnail","hentry","case_studies_region-deutschland","case_studies_region-deutschland-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Outdooractive : E-Mail-Zustellbarkeit verbessern in der Praxis<\/title>\n<meta name=\"description\" content=\"Case Study: Erfahren Sie, wie eine hohe E-Mail-Zustellbarkeit trotz komplexer Anforderungen erreicht werden kann, um Nutzer zu erreichen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/outdooractive\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Outdooractive : E-Mail-Zustellbarkeit verbessern in der Praxis\" \/>\n<meta property=\"og:description\" content=\"Case Study: Erfahren Sie, wie eine hohe E-Mail-Zustellbarkeit trotz komplexer Anforderungen erreicht werden kann, um Nutzer zu erreichen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/outdooractive\/\" \/>\n<meta property=\"og:site_name\" content=\"Mailjet: Email Delivery Service for Marketing &amp; Developer Teams\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-25T11:05:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/11\/MJ-CS-Outdooractive.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"496\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/outdooractive\\\/\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/outdooractive\\\/\",\"name\":\"Outdooractive : E-Mail-Zustellbarkeit verbessern in der Praxis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/outdooractive\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/outdooractive\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/MJ-CS-Outdooractive.jpg\",\"datePublished\":\"2025-11-11T15:32:07+00:00\",\"dateModified\":\"2026-02-25T11:05:31+00:00\",\"description\":\"Case Study: Erfahren Sie, wie eine hohe E-Mail-Zustellbarkeit trotz komplexer Anforderungen erreicht werden kann, um Nutzer zu erreichen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/outdooractive\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/outdooractive\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/outdooractive\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/MJ-CS-Outdooractive.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/MJ-CS-Outdooractive.jpg\",\"width\":800,\"height\":496},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/outdooractive\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Case Studies\",\"item\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Outdooractive\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/\",\"name\":\"Mailjet: Email Delivery Service for Marketing & Developer Teams\",\"description\":\"Discover our easy-to-use platform for designing and sending your email marketing campaigns, newsletters, and automated emails.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#organization\",\"name\":\"Mailjet: Email Delivery Service for Marketing & Developer Teams\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-mailjet-sinch.svg\",\"contentUrl\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-mailjet-sinch.svg\",\"width\":1,\"height\":1,\"caption\":\"Mailjet: Email Delivery Service for Marketing & Developer Teams\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Outdooractive : E-Mail-Zustellbarkeit verbessern in der Praxis","description":"Case Study: Erfahren Sie, wie eine hohe E-Mail-Zustellbarkeit trotz komplexer Anforderungen erreicht werden kann, um Nutzer zu erreichen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/outdooractive\/","og_locale":"de_DE","og_type":"article","og_title":"Outdooractive : E-Mail-Zustellbarkeit verbessern in der Praxis","og_description":"Case Study: Erfahren Sie, wie eine hohe E-Mail-Zustellbarkeit trotz komplexer Anforderungen erreicht werden kann, um Nutzer zu erreichen.","og_url":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/outdooractive\/","og_site_name":"Mailjet: Email Delivery Service for Marketing &amp; Developer Teams","article_modified_time":"2026-02-25T11:05:31+00:00","og_image":[{"width":800,"height":496,"url":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/11\/MJ-CS-Outdooractive.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/outdooractive\/","url":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/outdooractive\/","name":"Outdooractive : E-Mail-Zustellbarkeit verbessern in der Praxis","isPartOf":{"@id":"https:\/\/www.mailjet.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/outdooractive\/#primaryimage"},"image":{"@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/outdooractive\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/11\/MJ-CS-Outdooractive.jpg","datePublished":"2025-11-11T15:32:07+00:00","dateModified":"2026-02-25T11:05:31+00:00","description":"Case Study: Erfahren Sie, wie eine hohe E-Mail-Zustellbarkeit trotz komplexer Anforderungen erreicht werden kann, um Nutzer zu erreichen.","breadcrumb":{"@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/outdooractive\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/outdooractive\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/outdooractive\/#primaryimage","url":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/11\/MJ-CS-Outdooractive.jpg","contentUrl":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/11\/MJ-CS-Outdooractive.jpg","width":800,"height":496},{"@type":"BreadcrumbList","@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/outdooractive\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.mailjet.com\/de\/"},{"@type":"ListItem","position":2,"name":"Case Studies","item":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/"},{"@type":"ListItem","position":3,"name":"Outdooractive"}]},{"@type":"WebSite","@id":"https:\/\/www.mailjet.com\/de\/#website","url":"https:\/\/www.mailjet.com\/de\/","name":"Mailjet: Email Delivery Service for Marketing & Developer Teams","description":"Discover our easy-to-use platform for designing and sending your email marketing campaigns, newsletters, and automated emails.","publisher":{"@id":"https:\/\/www.mailjet.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mailjet.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.mailjet.com\/de\/#organization","name":"Mailjet: Email Delivery Service for Marketing & Developer Teams","url":"https:\/\/www.mailjet.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.mailjet.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/06\/logo-mailjet-sinch.svg","contentUrl":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/06\/logo-mailjet-sinch.svg","width":1,"height":1,"caption":"Mailjet: Email Delivery Service for Marketing & Developer Teams"},"image":{"@id":"https:\/\/www.mailjet.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/case-studies\/45891","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/case-studies"}],"about":[{"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/types\/case-studies"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/media\/46023"}],"wp:attachment":[{"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/media?parent=45891"}],"wp:term":[{"taxonomy":"case_studies_region","embeddable":true,"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/case_studies_region?post=45891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":45575,"date":"2025-10-23T14:28:04","date_gmt":"2025-10-23T14:28:04","guid":{"rendered":"https:\/\/www.mailjet.com\/resources\/case-studies\/my-askai\/"},"modified":"2025-10-23T14:28:05","modified_gmt":"2025-10-23T14:28:05","slug":"my-askai","status":"publish","type":"case-studies","link":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/my-askai\/","title":{"rendered":"My AskAI"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">My AskAI erschlie\u00dft mit Mailjets API einen neuen Einnahmekanal<\/h2>\n\n<p><a href=\"https:\/\/myaskai.com\/\">My AskAI<\/a> ist ein in Gro\u00dfbritannien ans\u00e4ssiges SaaS-Unternehmen, das Unternehmen bei der Automatisierung des Kundensupports durch KI-gest\u00fctzte Agenten unterst\u00fctzt. Diese Agenten lassen sich in Plattformen wie <a href=\"https:\/\/myaskai.com\/ai-agent-integration\/zendesk-tickets\">Zendesk<\/a>, <a href=\"https:\/\/myaskai.com\/ai-agent-integration\/intercom\">Intercom<\/a>, Gorgias und Freshdesk integrieren und l\u00f6sen \u00fcber 75% der Tickets automatisch, w\u00e4hrend sie komplexe Probleme an menschliche Teams weiterleiten.<\/p>\n\n<p>Die Mission: skalierbarer, sofortiger Support, der jede Kunden-E-Mail ohne Verz\u00f6gerung beantwortet.<\/p>\n    <div data-content-type=\"longform\" class=\"quote hub-quote longform-spacings d-flex flex-column rounded-lg px-5 py-6 px-md-6 py-md-7 p-lg-7 shadow-sm bg-primary\" data-theme=\"light\">\r\n\r\n        <div class=\"quote-logo mb-3\">\r\n                            <img decoding=\"async\" class=\"quote-logo\" src=\"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/10\/Circle-Logo.png\" alt=\"Zitat-Logo von Alex Rainey\">\r\n                    <\/div>\r\n\r\n        <blockquote class=\"quote-content content-body m-0 text-body-color\" id=\"quote-block-ba5e1604a092ffdc66cae256417e396e\">\r\n            Mailjet hat es uns erm\u00f6glicht, unseren KI-E-Mail-Assistenten einzuf\u00fchren &#8211; etwas, das vorher einfach nicht m\u00f6glich war. Das hat uns eine v\u00f6llig neue Funktion und einen neuen Umsatzkanal er\u00f6ffnet.        <\/blockquote>\r\n\r\n                    <div class=\"d-flex gap-3 mt-5\">\r\n                                    <div>\r\n                        <img decoding=\"async\" width=\"72\" height=\"72\" class=\"rounded-lg quote-author\" src=\"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/10\/Alex-R-Proflle-pic-scaled.jpg\" alt=\"Foto von Alex Rainey\">\r\n                    <\/div>\r\n                                <div class=\"d-flex flex-column align-self-center fs-sm\">\r\n                    <cite class=\"mb-0 fw-bold text-accent fst-normal\" aria-describedby=\"quote-block-ba5e1604a092ffdc66cae256417e396e\">\r\n                        Alex Rainey                    <\/cite>\r\n                                            <span class=\"mb-0 text-body-color\">CTO, My AskAI<\/span>\r\n                                    <\/div>\r\n            <\/div>\r\n            <\/div>\r\n\n<h2 class=\"wp-block-heading\">Herausforderung: Schaffung einer zuverl\u00e4ssigen Grundlage f\u00fcr KI-gesteuerte Unterst\u00fctzung<\/h2>\n\n<p>Um sein Versprechen einzul\u00f6sen, ben\u00f6tigte My AskAI eine zuverl\u00e4ssige Infrastruktur, um Tausende von KI-generierten Antworten in Echtzeit zu versenden und zu verfolgen.<\/p>\n\n<p>Die meisten E-Mail-Provider sind nicht f\u00fcr diesen Automatisierungsgrad ausgelegt, fehlende Nachrichten oder Verz\u00f6gerungen k\u00f6nnen zu frustrierten Kunden und Vertrauensverlust f\u00fchren.<\/p>\n    <div data-content-type=\"longform\" class=\"quote hub-quote longform-spacings d-flex flex-column rounded-lg px-5 py-6 px-md-6 py-md-7 p-lg-7 shadow-sm bg-primary\" data-theme=\"light\">\r\n\r\n        <div class=\"quote-logo mb-3\">\r\n                            <img decoding=\"async\" class=\"quote-logo\" src=\"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/10\/Circle-Logo.png\" alt=\"Zitat-Logo von Alex Rainey\">\r\n                    <\/div>\r\n\r\n        <blockquote class=\"quote-content content-body m-0 text-body-color\" id=\"quote-block-c9b4abc232c30021d8cf8ca99fce1095\">\r\n            Wir brauchten eine L\u00f6sung, mit der wir neue E-Mails abh\u00f6ren konnten, die auf einer benutzerdefinierten Domain eingingen. Diese E-Mails w\u00fcrden dann von unserem KI-Agenten verarbeitet werden, um eine automatische Antwort an den Kunden zu senden.        <\/blockquote>\r\n\r\n                    <div class=\"d-flex gap-3 mt-5\">\r\n                                    <div>\r\n                        <img decoding=\"async\" width=\"72\" height=\"72\" class=\"rounded-lg quote-author\" src=\"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/10\/Alex-R-Proflle-pic-scaled.jpg\" alt=\"Foto von Alex Rainey\">\r\n                    <\/div>\r\n                                <div class=\"d-flex flex-column align-self-center fs-sm\">\r\n                    <cite class=\"mb-0 fw-bold text-accent fst-normal\" aria-describedby=\"quote-block-c9b4abc232c30021d8cf8ca99fce1095\">\r\n                        Alex Rainey                    <\/cite>\r\n                                            <span class=\"mb-0 text-body-color\">CTO, My AskAI<\/span>\r\n                                    <\/div>\r\n            <\/div>\r\n            <\/div>\r\n\n<h2 class=\"wp-block-heading\">Die L\u00f6sung: Mailjets API erm\u00f6glichte die Automatisierung in Echtzeit<\/h2>\n\n<p>My AskAI wandte sich an Sinch Mailjet, weil es eine robuste, entwicklerfreundliche E-Mail-Infrastruktur ben\u00f6tigte, die mit Leichtigkeit gro\u00dfe Mengen automatisierter ausgehender E-Mails verarbeiten konnte.<\/p>\n\n<p>W\u00e4hrend die internen Systeme von My AskAI (integriert mit Zendesk und anderen Plattformen) eingehende E-Mails erfassen und KI-basierte Antworten generieren, sorgt Mailjet daf\u00fcr, dass jede Antwort den Kunden schnell und sicher erreicht und bildet das R\u00fcckgrat der Echtzeit-Supportfunktionen des Unternehmens.<\/p>\n\n<p>Mit der skalierbaren API und den Webhooks von Mailjet war My AskAI in der Lage:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>KI-generierte Antworten mit gleichbleibender Zustellbarkeit und Geschwindigkeit zu senden, damit keine Kundennachricht unbeantwortet bleibt.<\/li>\n\n\n\n<li>Die Zustellung und Interaktion \u00fcber die Mailjet-API zu verfolgen.<\/li>\n\n\n\n<li>Eine nahtlose Integration mit Zendesk, Intercom, Gorgias und Freshdesk, um automatisierte E-Mail-Antworten direkt aus bestehenden Workflows auszul\u00f6sen.<\/li>\n\n\n\n<li>Selbstbewusstes Skalieren unter 10\u00a0000 monatlichen E-Mails bei gleichzeitiger Planung f\u00fcr weiteres Wachstum.<\/li>\n<\/ul>\n    <div data-content-type=\"longform\" class=\"quote hub-quote longform-spacings d-flex flex-column rounded-lg px-5 py-6 px-md-6 py-md-7 p-lg-7 shadow-sm bg-primary\" data-theme=\"light\">\r\n\r\n        <div class=\"quote-logo mb-3\">\r\n                            <img decoding=\"async\" class=\"quote-logo\" src=\"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/10\/Circle-Logo.png\" alt=\"Zitat-Logo von Alex Rainey\">\r\n                    <\/div>\r\n\r\n        <blockquote class=\"quote-content content-body m-0 text-body-color\" id=\"quote-block-f9e8736b62bd7a3bab3de20acb4e75e6\">\r\n            Mailjet hat diese Funktion f\u00fcr uns und unsere Kunden vollst\u00e4ndig freigeschaltet. Dank der API und der Zuverl\u00e4ssigkeit des Systems ist die Verwaltung von E-Mails in gro\u00dfem Umfang m\u00fchelos.        <\/blockquote>\r\n\r\n                    <div class=\"d-flex gap-3 mt-5\">\r\n                                    <div>\r\n                        <img decoding=\"async\" width=\"72\" height=\"72\" class=\"rounded-lg quote-author\" src=\"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/10\/Alex-R-Proflle-pic-scaled.jpg\" alt=\"Foto von Alex Rainey\">\r\n                    <\/div>\r\n                                <div class=\"d-flex flex-column align-self-center fs-sm\">\r\n                    <cite class=\"mb-0 fw-bold text-accent fst-normal\" aria-describedby=\"quote-block-f9e8736b62bd7a3bab3de20acb4e75e6\">\r\n                        Alex Rainey                    <\/cite>\r\n                                            <span class=\"mb-0 text-body-color\">CTO, My AskAI<\/span>\r\n                                    <\/div>\r\n            <\/div>\r\n            <\/div>\r\n\n<p>Die Einrichtung war schnell und unkompliziert. Die Mailjet-API und die Dokumentation erm\u00f6glichten es dem Team, Webhooks zu konfigurieren und Nachrichten zu verwalten, ohne eine komplexe Infrastruktur von Grund auf aufzubauen.<\/p>\n\n<h2 class=\"wp-block-heading\">Ergebnisse: Antworten in Echtzeit, verl\u00e4ssliche Lieferung und zuverl\u00e4ssige Skalierung<\/h2>\n\n<p>Seit der Einf\u00fchrung von Mailjet ist My AskAI in der Lage:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Einen neuen KI-gesteuerten E-Mail-Assistenten zu starten, der bisher nicht m\u00f6glich war.<\/li>\n\n\n\n<li>Verpasste E-Mails zu eliminieren und sicher zu stellen, dass jedes Kundenticket erfasst wird.<\/li>\n\n\n\n<li>KI-Agenten zu nutzen, die es erm\u00f6glichen, sofort auf Kundenanfragen zu antworten<\/li>\n\n\n\n<li>Eine hervorragende Zustellbarkeit bei weniger als 10\u00a0000 E-Mails pro Monat aufrechterhalten<\/li>\n\n\n\n<li>Bauen Sie vertrauensvoll auf die Infrastruktur von Mailjet, um zuk\u00fcnftiges Wachstum zu unterst\u00fctzen.<\/li>\n<\/ul>\n    <div data-content-type=\"longform\" class=\"quote hub-quote longform-spacings d-flex flex-column rounded-lg px-5 py-6 px-md-6 py-md-7 p-lg-7 shadow-sm bg-primary\" data-theme=\"light\">\r\n\r\n        <div class=\"quote-logo mb-3\">\r\n                            <img decoding=\"async\" class=\"quote-logo\" src=\"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/10\/Circle-Logo.png\" alt=\"Zitat-Logo von Alex Rainey\">\r\n                    <\/div>\r\n\r\n        <blockquote class=\"quote-content content-body m-0 text-body-color\" id=\"quote-block-fe3542c13948b5148500cccd59b9a409\">\r\n            Die Nutzung der APIs und die Einrichtung der Webhooks sind sehr einfach.        <\/blockquote>\r\n\r\n                    <div class=\"d-flex gap-3 mt-5\">\r\n                                    <div>\r\n                        <img decoding=\"async\" width=\"72\" height=\"72\" class=\"rounded-lg quote-author\" src=\"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/10\/Alex-R-Proflle-pic-scaled.jpg\" alt=\"Foto von Alex Rainey\">\r\n                    <\/div>\r\n                                <div class=\"d-flex flex-column align-self-center fs-sm\">\r\n                    <cite class=\"mb-0 fw-bold text-accent fst-normal\" aria-describedby=\"quote-block-fe3542c13948b5148500cccd59b9a409\">\r\n                        Alex Rainey                    <\/cite>\r\n                                            <span class=\"mb-0 text-body-color\">CTO, My AskAI<\/span>\r\n                                    <\/div>\r\n            <\/div>\r\n            <\/div>\r\n\n<p>F\u00fcr die Zukunft plant das Team, die Zustellbarkeit weiter zu optimieren, um sicherzustellen, dass jede KI-gesteuerte Antwort den Kunden schnell und zuverl\u00e4ssig erreicht.<\/p>\n\n<h2 class=\"wp-block-heading\">Schlussfolgerung: Auf Skalierbarkeit ausgelegt, mit Mailjet als Basis<\/h2>\n\n<p>Mailjet stellte My AskAI die Infrastruktur zur Verf\u00fcgung, um eine gesch\u00e4ftskritische KI-Funktion einzuf\u00fchren und zu skalieren. Durch die Kombination von Flexibilit\u00e4t, zuverl\u00e4ssiger Zustellbarkeit und hervorragender Dokumentation hat Mailjet das Produkt von My AskAI nicht nur unterst\u00fctzt, sondern erweitert.<\/p>\n    <div data-content-type=\"longform\" class=\"quote hub-quote longform-spacings d-flex flex-column rounded-lg px-5 py-6 px-md-6 py-md-7 p-lg-7 shadow-sm bg-primary\" data-theme=\"light\">\r\n\r\n        <div class=\"quote-logo mb-3\">\r\n                            <img decoding=\"async\" class=\"quote-logo\" src=\"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/10\/Circle-Logo.png\" alt=\"Zitat-Logo von Alex Rainey\">\r\n                    <\/div>\r\n\r\n        <blockquote class=\"quote-content content-body m-0 text-body-color\" id=\"quote-block-4d9b57aba1a815569187ab4c2523a87a\">\r\n            Sehen Sie sich die API-Dokumente an. Es ist gro\u00dfartig.        <\/blockquote>\r\n\r\n                    <div class=\"d-flex gap-3 mt-5\">\r\n                                    <div>\r\n                        <img decoding=\"async\" width=\"72\" height=\"72\" class=\"rounded-lg quote-author\" src=\"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/10\/Alex-R-Proflle-pic-scaled.jpg\" alt=\"Foto von Alex Rainey\">\r\n                    <\/div>\r\n                                <div class=\"d-flex flex-column align-self-center fs-sm\">\r\n                    <cite class=\"mb-0 fw-bold text-accent fst-normal\" aria-describedby=\"quote-block-4d9b57aba1a815569187ab4c2523a87a\">\r\n                        Alex Rainey                    <\/cite>\r\n                                            <span class=\"mb-0 text-body-color\">CTO, My AskAI<\/span>\r\n                                    <\/div>\r\n            <\/div>\r\n            <\/div>\r\n","protected":false},"excerpt":{"rendered":"<p>Erfahren Sie, wie My AskAI die API von Mailjet nutzte, um KI-Antworten in Echtzeit auszul\u00f6sen und eine neue Produktfunktion einzuf\u00fchren, die zuvor nicht m\u00f6glich war.<\/p>\n","protected":false},"featured_media":45666,"template":"","meta":{"_acf_changed":false},"case_studies_region":[10139],"class_list":["post-45575","case-studies","type-case-studies","status-publish","has-post-thumbnail","hentry","case_studies_region-vereinigtes-konigreich"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>My AskAI - Mailjet: Email Delivery Service for Marketing &amp; Developer Teams<\/title>\n<meta name=\"description\" content=\"Erfahren Sie, wie My AskAI die API von Mailjet nutzte, um KI-Antworten in Echtzeit auszul\u00f6sen und eine neue Produktfunktion einzuf\u00fchren, die zuvor nicht m\u00f6glich war.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/my-askai\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"My AskAI - Mailjet: Email Delivery Service for Marketing &amp; Developer Teams\" \/>\n<meta property=\"og:description\" content=\"Erfahren Sie, wie My AskAI die API von Mailjet nutzte, um KI-Antworten in Echtzeit auszul\u00f6sen und eine neue Produktfunktion einzuf\u00fchren, die zuvor nicht m\u00f6glich war.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/my-askai\/\" \/>\n<meta property=\"og:site_name\" content=\"Mailjet: Email Delivery Service for Marketing &amp; Developer Teams\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-23T14:28:05+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/my-askai\\\/\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/my-askai\\\/\",\"name\":\"My AskAI - Mailjet: Email Delivery Service for Marketing &amp; Developer Teams\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/my-askai\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/my-askai\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/MJ-CS-MyAsk-AI.jpg\",\"datePublished\":\"2025-10-23T14:28:04+00:00\",\"dateModified\":\"2025-10-23T14:28:05+00:00\",\"description\":\"Erfahren Sie, wie My AskAI die API von Mailjet nutzte, um KI-Antworten in Echtzeit auszul\u00f6sen und eine neue Produktfunktion einzuf\u00fchren, die zuvor nicht m\u00f6glich war.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/my-askai\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/my-askai\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/my-askai\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/MJ-CS-MyAsk-AI.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/MJ-CS-MyAsk-AI.jpg\",\"width\":800,\"height\":496},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/my-askai\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Case Studies\",\"item\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"My AskAI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/\",\"name\":\"Mailjet: Email Delivery Service for Marketing & Developer Teams\",\"description\":\"Discover our easy-to-use platform for designing and sending your email marketing campaigns, newsletters, and automated emails.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#organization\",\"name\":\"Mailjet: Email Delivery Service for Marketing & Developer Teams\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-mailjet-sinch.svg\",\"contentUrl\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-mailjet-sinch.svg\",\"width\":1,\"height\":1,\"caption\":\"Mailjet: Email Delivery Service for Marketing & Developer Teams\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"My AskAI - Mailjet: Email Delivery Service for Marketing &amp; Developer Teams","description":"Erfahren Sie, wie My AskAI die API von Mailjet nutzte, um KI-Antworten in Echtzeit auszul\u00f6sen und eine neue Produktfunktion einzuf\u00fchren, die zuvor nicht m\u00f6glich war.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/my-askai\/","og_locale":"de_DE","og_type":"article","og_title":"My AskAI - Mailjet: Email Delivery Service for Marketing &amp; Developer Teams","og_description":"Erfahren Sie, wie My AskAI die API von Mailjet nutzte, um KI-Antworten in Echtzeit auszul\u00f6sen und eine neue Produktfunktion einzuf\u00fchren, die zuvor nicht m\u00f6glich war.","og_url":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/my-askai\/","og_site_name":"Mailjet: Email Delivery Service for Marketing &amp; Developer Teams","article_modified_time":"2025-10-23T14:28:05+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/my-askai\/","url":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/my-askai\/","name":"My AskAI - Mailjet: Email Delivery Service for Marketing &amp; Developer Teams","isPartOf":{"@id":"https:\/\/www.mailjet.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/my-askai\/#primaryimage"},"image":{"@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/my-askai\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/10\/MJ-CS-MyAsk-AI.jpg","datePublished":"2025-10-23T14:28:04+00:00","dateModified":"2025-10-23T14:28:05+00:00","description":"Erfahren Sie, wie My AskAI die API von Mailjet nutzte, um KI-Antworten in Echtzeit auszul\u00f6sen und eine neue Produktfunktion einzuf\u00fchren, die zuvor nicht m\u00f6glich war.","breadcrumb":{"@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/my-askai\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/my-askai\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/my-askai\/#primaryimage","url":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/10\/MJ-CS-MyAsk-AI.jpg","contentUrl":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/10\/MJ-CS-MyAsk-AI.jpg","width":800,"height":496},{"@type":"BreadcrumbList","@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/my-askai\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.mailjet.com\/de\/"},{"@type":"ListItem","position":2,"name":"Case Studies","item":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/"},{"@type":"ListItem","position":3,"name":"My AskAI"}]},{"@type":"WebSite","@id":"https:\/\/www.mailjet.com\/de\/#website","url":"https:\/\/www.mailjet.com\/de\/","name":"Mailjet: Email Delivery Service for Marketing & Developer Teams","description":"Discover our easy-to-use platform for designing and sending your email marketing campaigns, newsletters, and automated emails.","publisher":{"@id":"https:\/\/www.mailjet.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mailjet.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.mailjet.com\/de\/#organization","name":"Mailjet: Email Delivery Service for Marketing & Developer Teams","url":"https:\/\/www.mailjet.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.mailjet.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/06\/logo-mailjet-sinch.svg","contentUrl":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/06\/logo-mailjet-sinch.svg","width":1,"height":1,"caption":"Mailjet: Email Delivery Service for Marketing & Developer Teams"},"image":{"@id":"https:\/\/www.mailjet.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/case-studies\/45575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/case-studies"}],"about":[{"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/types\/case-studies"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/media\/45666"}],"wp:attachment":[{"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/media?parent=45575"}],"wp:term":[{"taxonomy":"case_studies_region","embeddable":true,"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/case_studies_region?post=45575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":42429,"date":"2025-10-09T15:14:11","date_gmt":"2025-10-09T15:14:11","guid":{"rendered":"https:\/\/www.mailjet.com\/?post_type=case-studies&#038;p=42429"},"modified":"2025-10-09T15:14:13","modified_gmt":"2025-10-09T15:14:13","slug":"sketchfab","status":"publish","type":"case-studies","link":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/sketchfab\/","title":{"rendered":"Sketchfab"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Sketchfab, Plattform f\u00fcr die gemeinsame Nutzung von 3D-Modellen, skaliert individuelle Benutzererfahrung mit transaktionaler E-Mail<\/h2>\n\n<p>Sketchfab, eine Plattform zum Ver\u00f6ffentlichen und Auffinden von 3D-Inhalten, will f\u00fcr die Sch\u00f6pfer von 3D-Inhalten das tun, was YouTube f\u00fcr Videomacher oder SoundCloud f\u00fcr Musiker getan hat. Transaktions-E-Mails sind ein wichtiger Teil der interaktiven Nutzererfahrung. Sketchfab sendet Benachrichtigungen \u00fcber Nutzerinteraktionen wie neue Kommentare, Follower und Likes. Sketchfab sendete mit ihrem eigenen SMTP, und als sie ihre Plattform skalieren wollten, beschlossen sie, nach einer zuverl\u00e4ssigeren, kosteng\u00fcnstigeren L\u00f6sung f\u00fcr den Versand von ausgel\u00f6sten E-Mails von ihren Servern aus zu suchen, und fanden Mailjet. &#8222;Die Umstellung von unserem eigenen SMTP war nur eine Frage der \u00c4nderung von ein paar Codezeilen&#8220;, sagt CPO Pierre-Antoine Passet. Sketchfab hat vor kurzem ein benutzerdefiniertes E-Mail-Pr\u00e4ferenzzentrum eingerichtet, in dem die Benutzer die Inhalte, die sie sehen, und die H\u00e4ufigkeit, mit der sie sie erhalten, anpassen k\u00f6nnen. Mithilfe der APIs von Mailjet kann Sketchfab individuelle Benutzerpr\u00e4ferenzen mit entsprechenden segmentierten Kontaktlisten synchronisieren. Wenn sich ein Nutzer von einer Art von &#8222;Aktivit\u00e4t&#8220; abmeldet, z. B. von Benachrichtigungen, wenn ihm jemand neu folgt, wird seine E-Mail-Adresse automatisch aus der entsprechenden Kontaktliste entfernt. Wenn man den Nutzern die M\u00f6glichkeit gibt, das Erlebnis auf ihre eigenen Bed\u00fcrfnisse zuzuschneiden, verbessert sich das Engagement.<\/p>\n    <div data-content-type=\"longform\" class=\"quote hub-quote longform-spacings d-flex flex-column rounded-lg px-5 py-6 px-md-6 py-md-7 p-lg-7 shadow-sm bg-primary\" data-theme=\"light\">\r\n\r\n        <div class=\"quote-logo mb-3\">\r\n                            <img decoding=\"async\" class=\"quote-logo\" src=\"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/01\/sketchfab.svg\" alt=\"Zitat-Logo von Pierre-Antoine Passet\">\r\n                    <\/div>\r\n\r\n        <blockquote class=\"quote-content content-body m-0 text-body-color\" id=\"quote-block-945447178c00cbfd3c15d769bbdff956\">\r\n            Die Umstellung von unserem eigenen SMTP war nur eine Frage der \u00c4nderung einiger Codezeilen&#8230; Das T\u00fcpfelchen auf dem i ist, dass einige Best Practices f\u00fcr die Zustellbarkeit integriert sind und andere von uns leicht automatisiert werden k\u00f6nnen, was die Verwaltung der Absenderreputation f\u00fcr uns zu einem Kinderspiel macht. Wenn zum Beispiel jemand eine unserer E-Mails als Spam markiert, wird seine Adresse automatisch aus unseren Verteilerlisten entfernt.        <\/blockquote>\r\n\r\n                    <div class=\"d-flex gap-3 mt-5\">\r\n                                    <div>\r\n                        <img decoding=\"async\" width=\"72\" height=\"72\" class=\"rounded-lg quote-author\" src=\"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/01\/Portrait-Pierre-Antoine-Passet-Sketchfab.png\" alt=\"Foto von Pierre-Antoine Passet\">\r\n                    <\/div>\r\n                                <div class=\"d-flex flex-column align-self-center fs-sm\">\r\n                    <cite class=\"mb-0 fw-bold text-accent fst-normal\" aria-describedby=\"quote-block-945447178c00cbfd3c15d769bbdff956\">\r\n                        Pierre-Antoine Passet                    <\/cite>\r\n                                            <span class=\"mb-0 text-body-color\">Leiter Produktmanagement (CPO) &#8211; Sketchfab<\/span>\r\n                                    <\/div>\r\n            <\/div>\r\n            <\/div>\r\n    <div data-content-type=\"longform\" class=\"longform-spacings\">\r\n        <div class=\"cta bg-primary rounded-lg px-5 py-6 p-md-7 px-md-6\">\r\n                    <div class=\"form-subscription\">\r\n                            <div class=\"h4 mb-3\">\r\n                    Keep me posted! Get great resources in your inbox every week.                <\/div>\r\n                                    <form accept-charset=\"UTF-8\" action=\"\" enctype=\"multipart\/form-data\" data-form-subscription method=\"POST\" style=\"max-width: 400px;\">\r\n                <div class=\"row justify-content-between align-items-top g-2\">\r\n                    <div class=\"col-10\">\r\n                        <input type=\"email\" name=\"email\" class=\"form-control\" placeholder=\"Email\" autocomplete=\"email\" required>\r\n                        <div data-fs=\"error\" role=\"alert\" class=\"invalid-feedback\">\r\n                            Please complete this required field.                        <\/div>\r\n                    <\/div>\r\n                                            <div class=\"col-12 order-last mt-3 fs-xxs\" data-fs=\"acceptance\" style=\"display:none;\">\r\n                            \r\n                                <div class=\"form-check\">\r\n                                    <input id=\"formSubscriptionAcceptance-terms-4362\" class=\"form-check-input\"\r\n                                        type=\"checkbox\" name=\"terms\">\r\n                                    <label for=\"formSubscriptionAcceptance-terms-4362\" class=\"form-check-label text-body-color\">\r\n                                        Ich habe die Servicebedingungen gelesen und stimme ihnen zu.                                        <span class=\"hs-form-required\">*<\/span>\r\n                                    <\/label>\r\n                                <\/div>\r\n\r\n                            \r\n                                <div class=\"form-check\">\r\n                                    <input id=\"formSubscriptionAcceptance-privacy-6333\" class=\"form-check-input\"\r\n                                        type=\"checkbox\" name=\"privacy\">\r\n                                    <label for=\"formSubscriptionAcceptance-privacy-6333\" class=\"form-check-label text-body-color\">\r\n                                        Ich habe die Datenschutzerkl\u00e4rung gelesen und bin damit einverstanden.                                        <span class=\"hs-form-required\">*<\/span>\r\n                                    <\/label>\r\n                                <\/div>\r\n\r\n                                                    <\/div>\r\n                    \r\n                                            <div class=\"col-12 order-last fs-xxs mb-0 mt-2 text-body-color\">\r\n                            Send me the Mailjet Newsletter.                        <\/div>\r\n                    \r\n                    <div class=\"col-2\">\r\n                        <button type=\"submit\" value=\"Submit\" aria-label=\"Submit\" class=\"btn btn-secondary btn-icon\">\r\n                            <svg aria-hidden=\"true\" data-url=\"https:\/\/www.mailjet.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/layout\/chevron-right.svg\"><\/svg>\r\n                        <\/button>\r\n                    <\/div>\r\n                <\/div>\r\n\r\n                <input type=\"hidden\" name=\"formSubscriptionRecaptchaToken\" data-fs=\"recaptcha-token\">\r\n\r\n            <\/form>\r\n            <div data-fs=\"message-success\" style=\"display: none;\">\r\n                <p class=\"mb-0 mt-2 text-body-color\">\r\n                    Check your inbox monthly for your Mailjet Newsletter!                <\/p>\r\n            <\/div>\r\n        <\/div>\r\n        <\/div>\r\n    <\/div>\r\n","protected":false},"excerpt":{"rendered":"<p>Lesen Sie weiter, um zu erfahren, wie Sketchfab sein Transaktions-E-Mail-System mit Mailjet skaliert und mit nur wenigen Zeilen Code die Zustellbarkeit, die Anpassbarkeit und das Engagement der Benutzer verbessert hat.<\/p>\n","protected":false},"featured_media":21575,"template":"","meta":{"_acf_changed":false},"case_studies_region":[10137],"class_list":["post-42429","case-studies","type-case-studies","status-publish","has-post-thumbnail","hentry","case_studies_region-usa-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sketchfab - E-Mail-Marketing - SMTP-Dienste | Mailjet<\/title>\n<meta name=\"description\" content=\"Sketchfab, eine Plattform zum Ver\u00f6ffentlichen und Auffinden von 3D-Inhalten, will f\u00fcr die Sch\u00f6pfer von 3D-Inhalten das tun, was YouTube f\u00fcr Videomacher oder SoundCloud f\u00fcr Musiker getan hat.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/sketchfab\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sketchfab - E-Mail-Marketing - SMTP-Dienste | Mailjet\" \/>\n<meta property=\"og:description\" content=\"Sketchfab, eine Plattform zum Ver\u00f6ffentlichen und Auffinden von 3D-Inhalten, will f\u00fcr die Sch\u00f6pfer von 3D-Inhalten das tun, was YouTube f\u00fcr Videomacher oder SoundCloud f\u00fcr Musiker getan hat.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/sketchfab\/\" \/>\n<meta property=\"og:site_name\" content=\"Mailjet: Email Delivery Service for Marketing &amp; Developer Teams\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-09T15:14:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/01\/Mailjet-Case-Study-Sketchfab.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"592\" \/>\n\t<meta property=\"og:image:height\" content=\"368\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/sketchfab\\\/\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/sketchfab\\\/\",\"name\":\"Sketchfab - E-Mail-Marketing - SMTP-Dienste | Mailjet\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/sketchfab\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/sketchfab\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Mailjet-Case-Study-Sketchfab.webp\",\"datePublished\":\"2025-10-09T15:14:11+00:00\",\"dateModified\":\"2025-10-09T15:14:13+00:00\",\"description\":\"Sketchfab, eine Plattform zum Ver\u00f6ffentlichen und Auffinden von 3D-Inhalten, will f\u00fcr die Sch\u00f6pfer von 3D-Inhalten das tun, was YouTube f\u00fcr Videomacher oder SoundCloud f\u00fcr Musiker getan hat.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/sketchfab\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/sketchfab\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/sketchfab\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Mailjet-Case-Study-Sketchfab.webp\",\"contentUrl\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Mailjet-Case-Study-Sketchfab.webp\",\"width\":592,\"height\":368},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/sketchfab\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Case Studies\",\"item\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sketchfab\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/\",\"name\":\"Mailjet: Email Delivery Service for Marketing & Developer Teams\",\"description\":\"Discover our easy-to-use platform for designing and sending your email marketing campaigns, newsletters, and automated emails.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#organization\",\"name\":\"Mailjet: Email Delivery Service for Marketing & Developer Teams\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-mailjet-sinch.svg\",\"contentUrl\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-mailjet-sinch.svg\",\"width\":1,\"height\":1,\"caption\":\"Mailjet: Email Delivery Service for Marketing & Developer Teams\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sketchfab - E-Mail-Marketing - SMTP-Dienste | Mailjet","description":"Sketchfab, eine Plattform zum Ver\u00f6ffentlichen und Auffinden von 3D-Inhalten, will f\u00fcr die Sch\u00f6pfer von 3D-Inhalten das tun, was YouTube f\u00fcr Videomacher oder SoundCloud f\u00fcr Musiker getan hat.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/sketchfab\/","og_locale":"de_DE","og_type":"article","og_title":"Sketchfab - E-Mail-Marketing - SMTP-Dienste | Mailjet","og_description":"Sketchfab, eine Plattform zum Ver\u00f6ffentlichen und Auffinden von 3D-Inhalten, will f\u00fcr die Sch\u00f6pfer von 3D-Inhalten das tun, was YouTube f\u00fcr Videomacher oder SoundCloud f\u00fcr Musiker getan hat.","og_url":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/sketchfab\/","og_site_name":"Mailjet: Email Delivery Service for Marketing &amp; Developer Teams","article_modified_time":"2025-10-09T15:14:13+00:00","og_image":[{"width":592,"height":368,"url":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/01\/Mailjet-Case-Study-Sketchfab.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/sketchfab\/","url":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/sketchfab\/","name":"Sketchfab - E-Mail-Marketing - SMTP-Dienste | Mailjet","isPartOf":{"@id":"https:\/\/www.mailjet.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/sketchfab\/#primaryimage"},"image":{"@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/sketchfab\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/01\/Mailjet-Case-Study-Sketchfab.webp","datePublished":"2025-10-09T15:14:11+00:00","dateModified":"2025-10-09T15:14:13+00:00","description":"Sketchfab, eine Plattform zum Ver\u00f6ffentlichen und Auffinden von 3D-Inhalten, will f\u00fcr die Sch\u00f6pfer von 3D-Inhalten das tun, was YouTube f\u00fcr Videomacher oder SoundCloud f\u00fcr Musiker getan hat.","breadcrumb":{"@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/sketchfab\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/sketchfab\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/sketchfab\/#primaryimage","url":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/01\/Mailjet-Case-Study-Sketchfab.webp","contentUrl":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/01\/Mailjet-Case-Study-Sketchfab.webp","width":592,"height":368},{"@type":"BreadcrumbList","@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/sketchfab\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.mailjet.com\/de\/"},{"@type":"ListItem","position":2,"name":"Case Studies","item":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/"},{"@type":"ListItem","position":3,"name":"Sketchfab"}]},{"@type":"WebSite","@id":"https:\/\/www.mailjet.com\/de\/#website","url":"https:\/\/www.mailjet.com\/de\/","name":"Mailjet: Email Delivery Service for Marketing & Developer Teams","description":"Discover our easy-to-use platform for designing and sending your email marketing campaigns, newsletters, and automated emails.","publisher":{"@id":"https:\/\/www.mailjet.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mailjet.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.mailjet.com\/de\/#organization","name":"Mailjet: Email Delivery Service for Marketing & Developer Teams","url":"https:\/\/www.mailjet.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.mailjet.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/06\/logo-mailjet-sinch.svg","contentUrl":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/06\/logo-mailjet-sinch.svg","width":1,"height":1,"caption":"Mailjet: Email Delivery Service for Marketing & Developer Teams"},"image":{"@id":"https:\/\/www.mailjet.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/case-studies\/42429","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/case-studies"}],"about":[{"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/types\/case-studies"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/media\/21575"}],"wp:attachment":[{"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/media?parent=42429"}],"wp:term":[{"taxonomy":"case_studies_region","embeddable":true,"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/case_studies_region?post=42429"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":42425,"date":"2025-10-09T15:06:25","date_gmt":"2025-10-09T15:06:25","guid":{"rendered":"https:\/\/www.mailjet.com\/?post_type=case-studies&#038;p=42425"},"modified":"2025-10-09T15:06:27","modified_gmt":"2025-10-09T15:06:27","slug":"uptopar-management","status":"publish","type":"case-studies","link":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/uptopar-management\/","title":{"rendered":"UpToPar-Management"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">UpToPar versendet E-Mails 3x schneller mit Mailjet<\/h2>\n\n<p>UpToPar ist das Unternehmen, das digitale Marketingaktivit\u00e4ten f\u00fcr Golfpl\u00e4tze, Resorts und Restaurants in den Vereinigten Staaten durchf\u00fchrt. F\u00fcr Kunden wie Berry Hill Resort und Lexington Golf &amp; Country Club bedeutet dies die Verwaltung von E-Mail, Social Media, Branding und mehr. Das bedeutet auch, dass die Belegschaft und der Kundenstamm weit verstreut sind, was eine nahtlose Zusammenarbeit zu einer der wichtigsten Priorit\u00e4ten f\u00fcr das Unternehmen macht.<\/p>\n\n<p>Bei anderen Kan\u00e4len, wie z. B. den sozialen Medien, wurde die Zusammenarbeit in alle Tools integriert, was die Durchf\u00fchrung von Kampagnen mit vielen Mitwirkenden f\u00fcr mehrere Kunden erleichtert. Alle Beteiligten konnten \u00fcber eine einzige Schnittstelle arbeiten, sie hatten Zugriff auf detaillierte Analysen und konnten Zeit sparen.<\/p>\n\n<p>Aus Sicht des Kunden bot das E-Mail-Programm von UpToPar einen Mehrwert f\u00fcr die Endbenutzer und sorgte f\u00fcr steigende Einnahmen. Auf der R\u00fcckseite hatte UpToPar jedoch mit Problemen zu k\u00e4mpfen, wie einem langsamen und komplexen E-Mail-Builder, dem Ausfall der E-Mail-Plattform und dem pl\u00f6tzlichen Verlust der gesamten Arbeit.<\/p>\n\n<p>Was die E-Mail anbelangt, waren die Tools von UpToPar einen Schritt zur\u00fcck. Das Marketingteam wusste, dass E-Mails das beste Preis-Leistungs-Verh\u00e4ltnis bieten, vor allem bei der Bewerbung von Veranstaltungen (die oft allein durch E-Mail-Werbung ausverkauft sind) und beim Versenden von Benachrichtigungen wie Reservierungs- und Abschlagserinnerungen.<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Statistiken zur Zeitverwendung:<\/strong> Das Team f\u00fchrte eine interne \u00dcberpr\u00fcfung der f\u00fcr E-Mail-Kampagnen aufgewendeten Zeit durch, um festzustellen, wo Zeit verloren ging und wo Effizienzsteigerungen erzielt werden konnten.<\/li>\n\n\n\n<li><strong>\u00dcberpr\u00fcfung des E-Mail-Dienstleisters:<\/strong> Sie ermittelten die wichtigsten Priorit\u00e4ten f\u00fcr einen E-Mail-Dienstanbieter und suchten nach einer L\u00f6sung, die diese Anforderungen erf\u00fcllt.<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\">Warum sollten Sie Mailjet w\u00e4hlen?<\/h2>\n\n<p>Die interne \u00dcberpr\u00fcfung von UpToPar ergab, dass im Durchschnitt 18 Stunden pro Woche mit dem Versand von E-Mails verbracht wurden. Da immer weniger Zeit zur Verf\u00fcgung stand, beschloss das Team, zu einem wesentlich schnelleren und teamfreundlicheren E-Mail-Anbieter zu wechseln. Die Antwort auf ihr Problem war Mailjet.<\/p>\n\n<p>Nach der Umstellung auf Mailjet f\u00fchrte UpToPar eine weitere \u00dcberpr\u00fcfung des Zeitaufwands f\u00fcr E-Mail-Kampagnen durch. Heute hat das Unternehmen den Zeitaufwand f\u00fcr Kampagnen um 66% reduziert, wobei die E-Mail-Manager nicht mehr als 6 Stunden pro Woche f\u00fcr Kampagnen aufwenden. Aus finanzieller Sicht spart das Unternehmen allein durch den Einsatz von Mailjet 12\u00a0480 $ an Zeit.<\/p>\n\n<p>Letztendlich entschied sich UpToPar f\u00fcr Mailjet, weil die Kollaborationstools, der intuitive E-Mail-Builder und Vorlagenmanager, die zuverl\u00e4ssige Infrastruktur und der Kundenerfolgsmanager von Mailjet den Vorzug vor anderen L\u00f6sungen erhielten.<\/p>\n\n<p>Nach einer internen Analyse der Art und Weise, wie das Marketingteam E-Mails erstellt und versendet, wurde klar, dass eine Plattform ben\u00f6tigt wurde, die f\u00fcr ein gro\u00dfes, dezentral arbeitendes Team konzipiert ist und auch externe Mitarbeiter wie Kunden einbeziehen kann.<\/p>\n\n<p>Mailjets Fokus auf Teams erm\u00f6glichte es UpToPar, seine vielen Kunden besser in einer Oberfl\u00e4che zu verwalten, sicherzustellen, dass Statistiken und Vorlagen \u00fcber verschiedene Kunden hinweg getrennt gehalten werden k\u00f6nnen, und schlie\u00dflich dabei zu helfen, E-Mails viel schneller als zuvor zu erstellen und zu versenden.<\/p>\n    <div data-content-type=\"longform\" class=\"quote hub-quote longform-spacings d-flex flex-column rounded-lg px-5 py-6 px-md-6 py-md-7 p-lg-7 shadow-sm bg-primary\" data-theme=\"light\">\r\n\r\n        <div class=\"quote-logo mb-3\">\r\n                            <img decoding=\"async\" class=\"quote-logo\" src=\"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/01\/uptopar.svg\" alt=\"Zitat-Logo von Natalia Contreras\">\r\n                    <\/div>\r\n\r\n        <blockquote class=\"quote-content content-body m-0 text-body-color\" id=\"quote-block-81409f24d04ab5a5ffd81da08c8975bb\">\r\n            Wir haben nicht nur Kosteneinsparungen durch ein besseres System erzielt, sondern unsere Abteilung ist jetzt auch effizienter als je zuvor. Ein gutes Beispiel f\u00fcr diese Ver\u00e4nderungen ist, dass wir aufgrund der erzielten Effizienz mit demselben Personal zwei Immobilien erwerben und zwei Beratungsvertr\u00e4ge abschlie\u00dfen konnten.          <\/blockquote>\r\n\r\n                    <div class=\"d-flex gap-3 mt-5\">\r\n                                    <div>\r\n                        <img decoding=\"async\" width=\"72\" height=\"72\" class=\"rounded-lg quote-author\" src=\"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/01\/Portrait-Natalia-Contreras-Up-To-Par.png\" alt=\"Foto von Natalia Contreras\">\r\n                    <\/div>\r\n                                <div class=\"d-flex flex-column align-self-center fs-sm\">\r\n                    <cite class=\"mb-0 fw-bold text-accent fst-normal\" aria-describedby=\"quote-block-81409f24d04ab5a5ffd81da08c8975bb\">\r\n                        Natalia Contreras                    <\/cite>\r\n                                            <span class=\"mb-0 text-body-color\">Direktorin f\u00fcr Marketing &#8211; UpToPar Management<\/span>\r\n                                    <\/div>\r\n            <\/div>\r\n            <\/div>\r\n\n<p>Mit Hilfe eines Kundenerfolgsmanagers hat UpToPar f\u00fcr jeden seiner Kunden ein Unterkonto eingerichtet und kann nun spezifische Benutzerrollen f\u00fcr verschiedene interne und externe Mitarbeiter zuweisen. So kann beispielsweise ein Texter f\u00fcr einen Kunden nicht auf den Rechnungsbereich oder die Vorlagen anderer Kunden zugreifen, es sei denn, er hat eine entsprechende Genehmigung.<\/p>\n\n<p>Au\u00dferdem k\u00f6nnen Kampagnen nicht ohne die Genehmigung eines Kundenmanagers verschickt werden, um sicherzustellen, dass Tipp- und Designfehler nicht durch die Maschen fallen.<\/p>\n    <div data-content-type=\"longform\" class=\"quote hub-quote longform-spacings d-flex flex-column rounded-lg px-5 py-6 px-md-6 py-md-7 p-lg-7 shadow-sm bg-primary\" data-theme=\"light\">\r\n\r\n        <div class=\"quote-logo mb-3\">\r\n                            <img decoding=\"async\" class=\"quote-logo\" src=\"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/01\/uptopar.svg\" alt=\"Zitat-Logo von Natalia Contreras\">\r\n                    <\/div>\r\n\r\n        <blockquote class=\"quote-content content-body m-0 text-body-color\" id=\"quote-block-adc97f54247a9134bcc4b8b70a38e987\">\r\n            Jetzt, wo wir mit Mailjet arbeiten, brauchen wir weniger als die H\u00e4lfte der Zeit, um Kampagnen zu erstellen.        <\/blockquote>\r\n\r\n                    <div class=\"d-flex gap-3 mt-5\">\r\n                                    <div>\r\n                        <img decoding=\"async\" width=\"72\" height=\"72\" class=\"rounded-lg quote-author\" src=\"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/01\/Portrait-Natalia-Contreras-Up-To-Par.png\" alt=\"Foto von Natalia Contreras\">\r\n                    <\/div>\r\n                                <div class=\"d-flex flex-column align-self-center fs-sm\">\r\n                    <cite class=\"mb-0 fw-bold text-accent fst-normal\" aria-describedby=\"quote-block-adc97f54247a9134bcc4b8b70a38e987\">\r\n                        Natalia Contreras                    <\/cite>\r\n                                            <span class=\"mb-0 text-body-color\">Direktorin f\u00fcr Marketing &#8211; UpToPar Management<\/span>\r\n                                    <\/div>\r\n            <\/div>\r\n            <\/div>\r\n\n<p>Dar\u00fcber hinaus konnte UpToPar durch die Zusammenarbeit mit dem Mailjet-Kundenerfolgsteam die \u00d6ffnungsraten erh\u00f6hen, indem es sich auf die Ansprache engagierter Nutzer konzentrierte und Kampagnen mit einer personalisierten, relevanten Botschaft versandte. In etwas mehr als einem Jahr sind die \u00d6ffnungsraten von UpToPar von 5% auf 30% gestiegen, und sie steigen weiter.<\/p>\n\n<h2 class=\"wp-block-heading\">Wie kann E-Mail Ihren ROI steigern?<\/h2>\n\n<p>UpToPar konnte nicht nur seine Effizienz beim Versand von E-Mails steigern, sondern auch den ROI einzelner Kampagnen deutlich erh\u00f6hen. Dies erm\u00f6glicht UpToPar, sich auf eigene Kan\u00e4le wie E-Mail-Marketing zu konzentrieren und Geld f\u00fcr Kan\u00e4le mit geringerer Wirkung wie Werbung in sozialen Medien auszugeben.<\/p>\n\n<p>Das UpToPar-Team ist nun f\u00fcr ein bedeutendes Wachstum in den n\u00e4chsten Jahren ger\u00fcstet, auch dank eines effizienteren E-Mail-Systems und eines validierten, umsatzsteigernden Kanals f\u00fcr Kampagnen.<\/p>\n\n<h2 class=\"wp-block-heading\">Zusammenfassung der Ergebnisse<\/h2>\n\n<p>In etwas mehr als einem Jahr war das UpToPar-Team in der Lage:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Verringerung des Zeitaufwands f\u00fcr E-Mails um 66\u00a0%, Einsparung von mehr als 12\u00a0000 $<\/li>\n\n\n\n<li>Erh\u00f6hung der \u00d6ffnungsrate um das 6-fache<\/li>\n\n\n\n<li>Erh\u00f6hung der Zahl der betreuten Kunden um 30\u00a0% bei gleichbleibendem Personalbestand<\/li>\n\n\n\n<li>Sparen Sie Geld f\u00fcr Werbung und andere Marketingkan\u00e4le durch eine optimierte E-Mail-Strategie<\/li>\n<\/ul>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"562\" height=\"317\" src=\"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/01\/UpToPar.png\" alt=\"Auf einem Laptop-Bildschirm angezeigte Website von Luxury Resorts mit einem malerischen Golfplatz und der &#xDC;berschrift &quot;Au&#xDF;ergew&#xF6;hnliche Erlebnisse&quot;.\" class=\"wp-image-41462\" srcset=\"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/01\/UpToPar.png 562w, https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/01\/UpToPar-300x169.png 300w\" sizes=\"(max-width: 562px) 100vw, 562px\" \/><\/figure>\n    <div data-content-type=\"longform\" class=\"longform-spacings\">\r\n        <div class=\"cta bg-primary rounded-lg px-5 py-6 p-md-7 px-md-6\">\r\n                    <div class=\"form-subscription\">\r\n                            <div class=\"h4 mb-3\">\r\n                    Keep me posted! Get great resources in your inbox every week.                <\/div>\r\n                                    <form accept-charset=\"UTF-8\" action=\"\" enctype=\"multipart\/form-data\" data-form-subscription method=\"POST\" style=\"max-width: 400px;\">\r\n                <div class=\"row justify-content-between align-items-top g-2\">\r\n                    <div class=\"col-10\">\r\n                        <input type=\"email\" name=\"email\" class=\"form-control\" placeholder=\"Email\" autocomplete=\"email\" required>\r\n                        <div data-fs=\"error\" role=\"alert\" class=\"invalid-feedback\">\r\n                            Please complete this required field.                        <\/div>\r\n                    <\/div>\r\n                                            <div class=\"col-12 order-last mt-3 fs-xxs\" data-fs=\"acceptance\" style=\"display:none;\">\r\n                            \r\n                                <div class=\"form-check\">\r\n                                    <input id=\"formSubscriptionAcceptance-terms-2270\" class=\"form-check-input\"\r\n                                        type=\"checkbox\" name=\"terms\">\r\n                                    <label for=\"formSubscriptionAcceptance-terms-2270\" class=\"form-check-label text-body-color\">\r\n                                        Ich habe die Servicebedingungen gelesen und stimme ihnen zu.                                        <span class=\"hs-form-required\">*<\/span>\r\n                                    <\/label>\r\n                                <\/div>\r\n\r\n                            \r\n                                <div class=\"form-check\">\r\n                                    <input id=\"formSubscriptionAcceptance-privacy-6003\" class=\"form-check-input\"\r\n                                        type=\"checkbox\" name=\"privacy\">\r\n                                    <label for=\"formSubscriptionAcceptance-privacy-6003\" class=\"form-check-label text-body-color\">\r\n                                        Ich habe die Datenschutzerkl\u00e4rung gelesen und bin damit einverstanden.                                        <span class=\"hs-form-required\">*<\/span>\r\n                                    <\/label>\r\n                                <\/div>\r\n\r\n                                                    <\/div>\r\n                    \r\n                                            <div class=\"col-12 order-last fs-xxs mb-0 mt-2 text-body-color\">\r\n                            Send me the Mailjet Newsletter.                        <\/div>\r\n                    \r\n                    <div class=\"col-2\">\r\n                        <button type=\"submit\" value=\"Submit\" aria-label=\"Submit\" class=\"btn btn-secondary btn-icon\">\r\n                            <svg aria-hidden=\"true\" data-url=\"https:\/\/www.mailjet.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/layout\/chevron-right.svg\"><\/svg>\r\n                        <\/button>\r\n                    <\/div>\r\n                <\/div>\r\n\r\n                <input type=\"hidden\" name=\"formSubscriptionRecaptchaToken\" data-fs=\"recaptcha-token\">\r\n\r\n            <\/form>\r\n            <div data-fs=\"message-success\" style=\"display: none;\">\r\n                <p class=\"mb-0 mt-2 text-body-color\">\r\n                    Check your inbox monthly for your Mailjet Newsletter!                <\/p>\r\n            <\/div>\r\n        <\/div>\r\n        <\/div>\r\n    <\/div>\r\n","protected":false},"excerpt":{"rendered":"<p>Lesen Sie weiter, um zu erfahren, wie UpToPar seine E-Mail-Abl\u00e4ufe mit Mailjet rationalisiert hat und dadurch Zeit und Ressourcen freisetzte, um sich auf das Wachstum zu konzentrieren.<\/p>\n","protected":false},"featured_media":21588,"template":"","meta":{"_acf_changed":false},"case_studies_region":[10137],"class_list":["post-42425","case-studies","type-case-studies","status-publish","has-post-thumbnail","hentry","case_studies_region-usa-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>UpToPar Management - E-Mail-Marketing - SMTP-Dienste | Mailjet<\/title>\n<meta name=\"description\" content=\"UpToPar verwaltet das Marketing f\u00fcr Resorts, Hotels und Golfpl\u00e4tze in den gesamten Vereinigten Staaten.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/uptopar-management\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"UpToPar Management - E-Mail-Marketing - SMTP-Dienste | Mailjet\" \/>\n<meta property=\"og:description\" content=\"UpToPar verwaltet das Marketing f\u00fcr Resorts, Hotels und Golfpl\u00e4tze in den gesamten Vereinigten Staaten.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/uptopar-management\/\" \/>\n<meta property=\"og:site_name\" content=\"Mailjet: Email Delivery Service for Marketing &amp; Developer Teams\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-09T15:06:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/01\/Mailjet-Case-Study-Up-To-Par.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"592\" \/>\n\t<meta property=\"og:image:height\" content=\"368\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"5\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/uptopar-management\\\/\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/uptopar-management\\\/\",\"name\":\"UpToPar Management - E-Mail-Marketing - SMTP-Dienste | Mailjet\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/uptopar-management\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/uptopar-management\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Mailjet-Case-Study-Up-To-Par.webp\",\"datePublished\":\"2025-10-09T15:06:25+00:00\",\"dateModified\":\"2025-10-09T15:06:27+00:00\",\"description\":\"UpToPar verwaltet das Marketing f\u00fcr Resorts, Hotels und Golfpl\u00e4tze in den gesamten Vereinigten Staaten.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/uptopar-management\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/uptopar-management\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/uptopar-management\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Mailjet-Case-Study-Up-To-Par.webp\",\"contentUrl\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Mailjet-Case-Study-Up-To-Par.webp\",\"width\":592,\"height\":368},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/uptopar-management\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Case Studies\",\"item\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"UpToPar-Management\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/\",\"name\":\"Mailjet: Email Delivery Service for Marketing & Developer Teams\",\"description\":\"Discover our easy-to-use platform for designing and sending your email marketing campaigns, newsletters, and automated emails.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#organization\",\"name\":\"Mailjet: Email Delivery Service for Marketing & Developer Teams\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-mailjet-sinch.svg\",\"contentUrl\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-mailjet-sinch.svg\",\"width\":1,\"height\":1,\"caption\":\"Mailjet: Email Delivery Service for Marketing & Developer Teams\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"UpToPar Management - E-Mail-Marketing - SMTP-Dienste | Mailjet","description":"UpToPar verwaltet das Marketing f\u00fcr Resorts, Hotels und Golfpl\u00e4tze in den gesamten Vereinigten Staaten.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/uptopar-management\/","og_locale":"de_DE","og_type":"article","og_title":"UpToPar Management - E-Mail-Marketing - SMTP-Dienste | Mailjet","og_description":"UpToPar verwaltet das Marketing f\u00fcr Resorts, Hotels und Golfpl\u00e4tze in den gesamten Vereinigten Staaten.","og_url":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/uptopar-management\/","og_site_name":"Mailjet: Email Delivery Service for Marketing &amp; Developer Teams","article_modified_time":"2025-10-09T15:06:27+00:00","og_image":[{"width":592,"height":368,"url":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/01\/Mailjet-Case-Study-Up-To-Par.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"5\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/uptopar-management\/","url":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/uptopar-management\/","name":"UpToPar Management - E-Mail-Marketing - SMTP-Dienste | Mailjet","isPartOf":{"@id":"https:\/\/www.mailjet.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/uptopar-management\/#primaryimage"},"image":{"@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/uptopar-management\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/01\/Mailjet-Case-Study-Up-To-Par.webp","datePublished":"2025-10-09T15:06:25+00:00","dateModified":"2025-10-09T15:06:27+00:00","description":"UpToPar verwaltet das Marketing f\u00fcr Resorts, Hotels und Golfpl\u00e4tze in den gesamten Vereinigten Staaten.","breadcrumb":{"@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/uptopar-management\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/uptopar-management\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/uptopar-management\/#primaryimage","url":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/01\/Mailjet-Case-Study-Up-To-Par.webp","contentUrl":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/01\/Mailjet-Case-Study-Up-To-Par.webp","width":592,"height":368},{"@type":"BreadcrumbList","@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/uptopar-management\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.mailjet.com\/de\/"},{"@type":"ListItem","position":2,"name":"Case Studies","item":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/"},{"@type":"ListItem","position":3,"name":"UpToPar-Management"}]},{"@type":"WebSite","@id":"https:\/\/www.mailjet.com\/de\/#website","url":"https:\/\/www.mailjet.com\/de\/","name":"Mailjet: Email Delivery Service for Marketing & Developer Teams","description":"Discover our easy-to-use platform for designing and sending your email marketing campaigns, newsletters, and automated emails.","publisher":{"@id":"https:\/\/www.mailjet.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mailjet.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.mailjet.com\/de\/#organization","name":"Mailjet: Email Delivery Service for Marketing & Developer Teams","url":"https:\/\/www.mailjet.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.mailjet.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/06\/logo-mailjet-sinch.svg","contentUrl":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/06\/logo-mailjet-sinch.svg","width":1,"height":1,"caption":"Mailjet: Email Delivery Service for Marketing & Developer Teams"},"image":{"@id":"https:\/\/www.mailjet.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/case-studies\/42425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/case-studies"}],"about":[{"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/types\/case-studies"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/media\/21588"}],"wp:attachment":[{"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/media?parent=42425"}],"wp:term":[{"taxonomy":"case_studies_region","embeddable":true,"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/case_studies_region?post=42425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":42426,"date":"2025-10-09T15:04:34","date_gmt":"2025-10-09T15:04:34","guid":{"rendered":"https:\/\/www.mailjet.com\/?post_type=case-studies&#038;p=42426"},"modified":"2025-10-09T15:04:36","modified_gmt":"2025-10-09T15:04:36","slug":"mention-me","status":"publish","type":"case-studies","link":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/mention-me\/","title":{"rendered":"Mention Me"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Mention Me steigert die Neukundengewinnung durch Empfehlungen um 10-25%<\/h2>\n\n<p>Mention Me, ein in Gro\u00dfbritannien ans\u00e4ssiges Technologieunternehmen, ist eine Plattform, mit der Unternehmen Empfehlungsprogramme erstellen und optimieren k\u00f6nnen. Der Dienst bietet eine Peer-to-Peer-Empfehlungsfunktion, bei der sich die Nutzer unter anderem gegenseitig Empfehlungsangebote per E-Mail schicken k\u00f6nnen, die von Mailjet bereitgestellt werden. Als Mention Me gegr\u00fcndet wurde, war das Team auf der Suche nach einer skalierbaren und sicheren E-Mail-Transaktionsl\u00f6sung. Da Mention Me im Auftrag von Kunden arbeitet, hatten der Schutz personenbezogener Daten und solide rechtliche Bedingungen oberste Priorit\u00e4t. In den letzten zwei Jahren ist Mention Me auf die Zusammenarbeit mit nationalen und internationalen Marken angewachsen, mit einem Wachstum von mehr als 1000\u00a0% im E-Mail-Versandvolumen. Sie haben Transaktions-E-Mails, die von Mailjet geliefert werden, genutzt, um ihren Kerngesch\u00e4ftswert zu steigern und einen Zuwachs von 10 bis 25\u00a0% an Neukunden f\u00fcr ihre Kunden durch diesen Service zu erzielen.<\/p>\n    <div data-content-type=\"longform\" class=\"quote hub-quote longform-spacings d-flex flex-column rounded-lg px-5 py-6 px-md-6 py-md-7 p-lg-7 shadow-sm bg-primary\" data-theme=\"light\">\r\n\r\n        <div class=\"quote-logo mb-3\">\r\n                            <img decoding=\"async\" class=\"quote-logo\" src=\"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/01\/mentionme.svg\" alt=\"Zitat-Logo von Tim Boughton\">\r\n                    <\/div>\r\n\r\n        <blockquote class=\"quote-content content-body m-0 text-body-color\" id=\"quote-block-2514f1e7954dc64c7dd9eeaca2409454\">\r\n            Letztlich kommt es darauf an, dass unsere E-Mails schnell und effizient an den Empf\u00e4nger zugestellt werden. Wir haben Vertrauen in die Leistung, Lieferf\u00e4higkeit und Zuverl\u00e4ssigkeit der Plattform. Wir haben viele andere Dinge, auf die wir uns konzentrieren m\u00fcssen, wenn wir unser Gesch\u00e4ft ausbauen &#8211; da ist es gut, dass wir uns bei der Zustellung unserer E-Mails auf einen Partner wie Mailjet verlassen k\u00f6nnen.        <\/blockquote>\r\n\r\n                    <div class=\"d-flex gap-3 mt-5\">\r\n                                    <div>\r\n                        <img decoding=\"async\" width=\"72\" height=\"72\" class=\"rounded-lg quote-author\" src=\"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/01\/Portrait-Tim-Boughton-Mention-Me.png\" alt=\"Foto von Tim Boughton\">\r\n                    <\/div>\r\n                                <div class=\"d-flex flex-column align-self-center fs-sm\">\r\n                    <cite class=\"mb-0 fw-bold text-accent fst-normal\" aria-describedby=\"quote-block-2514f1e7954dc64c7dd9eeaca2409454\">\r\n                        Tim Boughton                    <\/cite>\r\n                                            <span class=\"mb-0 text-body-color\">CTO &#8211; Mention Me<\/span>\r\n                                    <\/div>\r\n            <\/div>\r\n            <\/div>\r\n    <div data-content-type=\"longform\" class=\"longform-spacings\">\r\n        <div class=\"cta bg-primary rounded-lg px-5 py-6 p-md-7 px-md-6\">\r\n                    <div class=\"form-subscription\">\r\n                            <div class=\"h4 mb-3\">\r\n                    Keep me posted! Get great resources in your inbox every week.                <\/div>\r\n                                    <form accept-charset=\"UTF-8\" action=\"\" enctype=\"multipart\/form-data\" data-form-subscription method=\"POST\" style=\"max-width: 400px;\">\r\n                <div class=\"row justify-content-between align-items-top g-2\">\r\n                    <div class=\"col-10\">\r\n                        <input type=\"email\" name=\"email\" class=\"form-control\" placeholder=\"Email\" autocomplete=\"email\" required>\r\n                        <div data-fs=\"error\" role=\"alert\" class=\"invalid-feedback\">\r\n                            Please complete this required field.                        <\/div>\r\n                    <\/div>\r\n                                            <div class=\"col-12 order-last mt-3 fs-xxs\" data-fs=\"acceptance\" style=\"display:none;\">\r\n                            \r\n                                <div class=\"form-check\">\r\n                                    <input id=\"formSubscriptionAcceptance-terms-8949\" class=\"form-check-input\"\r\n                                        type=\"checkbox\" name=\"terms\">\r\n                                    <label for=\"formSubscriptionAcceptance-terms-8949\" class=\"form-check-label text-body-color\">\r\n                                        Ich habe die Servicebedingungen gelesen und stimme ihnen zu.                                        <span class=\"hs-form-required\">*<\/span>\r\n                                    <\/label>\r\n                                <\/div>\r\n\r\n                            \r\n                                <div class=\"form-check\">\r\n                                    <input id=\"formSubscriptionAcceptance-privacy-6202\" class=\"form-check-input\"\r\n                                        type=\"checkbox\" name=\"privacy\">\r\n                                    <label for=\"formSubscriptionAcceptance-privacy-6202\" class=\"form-check-label text-body-color\">\r\n                                        Ich habe die Datenschutzerkl\u00e4rung gelesen und bin damit einverstanden.                                        <span class=\"hs-form-required\">*<\/span>\r\n                                    <\/label>\r\n                                <\/div>\r\n\r\n                                                    <\/div>\r\n                    \r\n                                            <div class=\"col-12 order-last fs-xxs mb-0 mt-2 text-body-color\">\r\n                            Send me the Mailjet Newsletter.                        <\/div>\r\n                    \r\n                    <div class=\"col-2\">\r\n                        <button type=\"submit\" value=\"Submit\" aria-label=\"Submit\" class=\"btn btn-secondary btn-icon\">\r\n                            <svg aria-hidden=\"true\" data-url=\"https:\/\/www.mailjet.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/layout\/chevron-right.svg\"><\/svg>\r\n                        <\/button>\r\n                    <\/div>\r\n                <\/div>\r\n\r\n                <input type=\"hidden\" name=\"formSubscriptionRecaptchaToken\" data-fs=\"recaptcha-token\">\r\n\r\n            <\/form>\r\n            <div data-fs=\"message-success\" style=\"display: none;\">\r\n                <p class=\"mb-0 mt-2 text-body-color\">\r\n                    Check your inbox monthly for your Mailjet Newsletter!                <\/p>\r\n            <\/div>\r\n        <\/div>\r\n        <\/div>\r\n    <\/div>\r\n","protected":false},"excerpt":{"rendered":"<p>Lesen Sie weiter, um zu erfahren, wie Mention Me seine Empfehlungsplattform mit Transaktions-E-Mails von Mailjet skaliert hat, um die Kundenakquisitionsraten zu steigern und gleichzeitig eine sichere Zustellung mit hohem Volumen zu gew\u00e4hrleisten.<\/p>\n","protected":false},"featured_media":21565,"template":"","meta":{"_acf_changed":false},"case_studies_region":[10139],"class_list":["post-42426","case-studies","type-case-studies","status-publish","has-post-thumbnail","hentry","case_studies_region-vereinigtes-konigreich"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mention Me - E-Mail-Marketing - SMTP-Dienste | Mailjet<\/title>\n<meta name=\"description\" content=\"Mention Me, ein in Gro\u00dfbritannien ans\u00e4ssiges Technologieunternehmen, ist eine Plattform, mit der Unternehmen Empfehlungsprogramme erstellen und optimieren k\u00f6nnen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/mention-me\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mention Me - E-Mail-Marketing - SMTP-Dienste | Mailjet\" \/>\n<meta property=\"og:description\" content=\"Mention Me, ein in Gro\u00dfbritannien ans\u00e4ssiges Technologieunternehmen, ist eine Plattform, mit der Unternehmen Empfehlungsprogramme erstellen und optimieren k\u00f6nnen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/mention-me\/\" \/>\n<meta property=\"og:site_name\" content=\"Mailjet: Email Delivery Service for Marketing &amp; Developer Teams\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-09T15:04:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/01\/Mailjet-Case-Study-Mention-Me.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"592\" \/>\n\t<meta property=\"og:image:height\" content=\"368\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/mention-me\\\/\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/mention-me\\\/\",\"name\":\"Mention Me - E-Mail-Marketing - SMTP-Dienste | Mailjet\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/mention-me\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/mention-me\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Mailjet-Case-Study-Mention-Me.webp\",\"datePublished\":\"2025-10-09T15:04:34+00:00\",\"dateModified\":\"2025-10-09T15:04:36+00:00\",\"description\":\"Mention Me, ein in Gro\u00dfbritannien ans\u00e4ssiges Technologieunternehmen, ist eine Plattform, mit der Unternehmen Empfehlungsprogramme erstellen und optimieren k\u00f6nnen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/mention-me\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/mention-me\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/mention-me\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Mailjet-Case-Study-Mention-Me.webp\",\"contentUrl\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Mailjet-Case-Study-Mention-Me.webp\",\"width\":592,\"height\":368},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/mention-me\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Case Studies\",\"item\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/ressourcen\\\/fallstudien\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mention Me\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/\",\"name\":\"Mailjet: Email Delivery Service for Marketing & Developer Teams\",\"description\":\"Discover our easy-to-use platform for designing and sending your email marketing campaigns, newsletters, and automated emails.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#organization\",\"name\":\"Mailjet: Email Delivery Service for Marketing & Developer Teams\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-mailjet-sinch.svg\",\"contentUrl\":\"https:\\\/\\\/www.mailjet.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-mailjet-sinch.svg\",\"width\":1,\"height\":1,\"caption\":\"Mailjet: Email Delivery Service for Marketing & Developer Teams\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mailjet.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mention Me - E-Mail-Marketing - SMTP-Dienste | Mailjet","description":"Mention Me, ein in Gro\u00dfbritannien ans\u00e4ssiges Technologieunternehmen, ist eine Plattform, mit der Unternehmen Empfehlungsprogramme erstellen und optimieren k\u00f6nnen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/mention-me\/","og_locale":"de_DE","og_type":"article","og_title":"Mention Me - E-Mail-Marketing - SMTP-Dienste | Mailjet","og_description":"Mention Me, ein in Gro\u00dfbritannien ans\u00e4ssiges Technologieunternehmen, ist eine Plattform, mit der Unternehmen Empfehlungsprogramme erstellen und optimieren k\u00f6nnen.","og_url":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/mention-me\/","og_site_name":"Mailjet: Email Delivery Service for Marketing &amp; Developer Teams","article_modified_time":"2025-10-09T15:04:36+00:00","og_image":[{"width":592,"height":368,"url":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/01\/Mailjet-Case-Study-Mention-Me.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/mention-me\/","url":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/mention-me\/","name":"Mention Me - E-Mail-Marketing - SMTP-Dienste | Mailjet","isPartOf":{"@id":"https:\/\/www.mailjet.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/mention-me\/#primaryimage"},"image":{"@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/mention-me\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/01\/Mailjet-Case-Study-Mention-Me.webp","datePublished":"2025-10-09T15:04:34+00:00","dateModified":"2025-10-09T15:04:36+00:00","description":"Mention Me, ein in Gro\u00dfbritannien ans\u00e4ssiges Technologieunternehmen, ist eine Plattform, mit der Unternehmen Empfehlungsprogramme erstellen und optimieren k\u00f6nnen.","breadcrumb":{"@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/mention-me\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/mention-me\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/mention-me\/#primaryimage","url":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/01\/Mailjet-Case-Study-Mention-Me.webp","contentUrl":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/01\/Mailjet-Case-Study-Mention-Me.webp","width":592,"height":368},{"@type":"BreadcrumbList","@id":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/mention-me\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.mailjet.com\/de\/"},{"@type":"ListItem","position":2,"name":"Case Studies","item":"https:\/\/www.mailjet.com\/de\/ressourcen\/fallstudien\/"},{"@type":"ListItem","position":3,"name":"Mention Me"}]},{"@type":"WebSite","@id":"https:\/\/www.mailjet.com\/de\/#website","url":"https:\/\/www.mailjet.com\/de\/","name":"Mailjet: Email Delivery Service for Marketing & Developer Teams","description":"Discover our easy-to-use platform for designing and sending your email marketing campaigns, newsletters, and automated emails.","publisher":{"@id":"https:\/\/www.mailjet.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mailjet.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.mailjet.com\/de\/#organization","name":"Mailjet: Email Delivery Service for Marketing & Developer Teams","url":"https:\/\/www.mailjet.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.mailjet.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/06\/logo-mailjet-sinch.svg","contentUrl":"https:\/\/www.mailjet.com\/wp-content\/uploads\/2025\/06\/logo-mailjet-sinch.svg","width":1,"height":1,"caption":"Mailjet: Email Delivery Service for Marketing & Developer Teams"},"image":{"@id":"https:\/\/www.mailjet.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/case-studies\/42426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/case-studies"}],"about":[{"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/types\/case-studies"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/media\/21565"}],"wp:attachment":[{"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/media?parent=42426"}],"wp:term":[{"taxonomy":"case_studies_region","embeddable":true,"href":"https:\/\/www.mailjet.com\/de\/wp-json\/wp\/v2\/case_studies_region?post=42426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}]